{"id":2245,"date":"2020-10-25T13:55:41","date_gmt":"2020-10-25T12:55:41","guid":{"rendered":"https:\/\/www.eren.ch\/barc\/?p=2245"},"modified":"2020-10-27T10:30:37","modified_gmt":"2020-10-27T09:30:37","slug":"la-loi-du-boomerang","status":"publish","type":"post","link":"https:\/\/www.eren.ch\/barc\/2020\/10\/25\/la-loi-du-boomerang\/","title":{"rendered":"La loi du boomerang"},"content":{"rendered":"<p>Culte d&rsquo;accueil des nouveaux cat\u00e9chum\u00e8nes et reconnaissance pour les jeunes moniteurs\u00b7trices des paroisses de La BARC et du Joran.<\/p>\n<p>Par Antoine Staffelbach, Manon Schneider, Olivier Junod, C\u00e9cile Guinand, Sarah Badertscher et Diane Friedli.<\/p>\n<h2>Accueil<\/h2>\n<blockquote>\n<p style=\"text-align: left;\">M\u00eame si les collines venaient \u00e0 s&rsquo;\u00e9branler, m\u00eame si les montagnes venaient \u00e0 changer de place, l&rsquo;amour que j&rsquo;ai pour toi ne changera jamais et mon alliance de paix avec toi restera in\u00e9branlable. C&rsquo;est moi, le Seigneur, qui te le dis, moi qui te garde ma tendresse.<br \/>\n\u00c9sa\u00efe 54\/10<\/p>\n<\/blockquote>\n<p>C\u2019est avec cette promesse, que les croyants qui nous ont pr\u00e9c\u00e9d\u00e9s au fil des si\u00e8cles ont re\u00e7ue pour leur vie, que nous vous accueillons ce matin. Recevez \u00e0 votre tour, cette promesse pour votre vie : La gr\u00e2ce et la paix nous sont donn\u00e9es par Dieu, lui qui est P\u00e8re, Fils et Esprit Saint. Amen<\/p>\n<p>La c\u00e9l\u00e9bration de ce jour est un moment important pour la communaut\u00e9 des paroisses de La BARC et du Joran: temps d\u2019accueil des cat\u00e9chum\u00e8nes qui se lancent dans l\u2019ann\u00e9e de KT, temps de reconnaissance pour les moniteurs qui s\u2019engagent \u00e0 les accompagne. Bienvenue \u00e0 vous, ch\u00e8res familles, chers paroissiens, qui \u00eates venus les entourer.<\/p>\n<p>En ces temps troubl\u00e9s, notre monde n\u2019est plus tout \u00e0 fait le m\u00eame que l\u2019an dernier. Des gestes qui nous paraissaient anodins (serrer la main, faire la bise) sont devenus interdits. Le masque sur les visages est devenu la norme. Alors que nos certitudes sont \u00e9branl\u00e9es, nous tendons l\u2019oreille \u00e0 la promesse de Dieu: m\u00eame si le monde venait \u00e0 s\u2019\u00e9crouler, mon amour pour toi ne changera jamais!<\/p>\n<h2>Pri\u00e8re d&rsquo;invocation<\/h2>\n<p>Seigneur Dieu, merci pour ta pr\u00e9sence qui jamais ne se d\u00e9ment. En aucune circonstance, tu nous laisses seuls, livr\u00e9s \u00e0 nous-m\u00eames. Car ton amour pour nous est \u00e0 toute \u00e9preuve.<\/p>\n<p>Lorsque je me sens seul, je repense \u00e0 cette parole\u00a0: \u00ab\u00a0Demandez et vous recevrez. Cherchez et vous trouverez.\u00a0\u00bb Et je cherche ta pr\u00e9sence pr\u00e8s de moi.<\/p>\n<p>Sois pr\u00e9sent au milieu de nous ce matin.<br \/>\nQue par nos paroles \u00e9chang\u00e9es, nos signes d\u2019amiti\u00e9, nos encouragements et le partage de notre foi, nous puissions te d\u00e9couvrir.<\/p>\n<p>Sois pr\u00e9sent avec nous durant toute cette ann\u00e9e de cat\u00e9chisme. Quand nous serons r\u00e9unis aussi bien que dans nos vies individuelles.<\/p>\n<p>Seigneur Dieu, merci pour ta pr\u00e9sence qui jamais ne se d\u00e9ment. Amen<\/p>\n<h2>Reconnaissance<\/h2>\n<p>Notre \u00c9glise a la chance, chaque ann\u00e9e et dans toutes les paroisses, de pouvoir compter sur des personnes qui choisissent de s\u2019engager dans l\u2019animation du cat\u00e9chisme. Cette ann\u00e9e nous pouvons compter sur des Jefs (jeunes en formation) et des Jacs (jeunes accompagnant\u00b7e\u00b7s de KT) qui sont en train de faire la formation de moniteurs\u00b7trices et sur des personnes qui sont engag\u00e9es depuis plusieurs ann\u00e9es dans le KT, moniteurs\u00b7trices dipl\u00f4m\u00e9\u00b7e\u00b7s et professionnel\u00b7le\u00b7s. Ensemble, ils\u00b7elles forment le groupe de l\u2019\u00c9toile.<\/p>\n<p>Nous sommes reconnaissants de pouvoir compter sur vous pour le cat\u00e9chisme! Nous aimerions maintenant vous porter dans la pri\u00e8re pour cette ann\u00e9e de cat\u00e9chisme qui s\u2019ouvre devant vous.<\/p>\n<p>Seigneur,<br \/>\nNous te disons merci pour ces personnes qui s\u2019engagent pour offrir aux jeunes la possibilit\u00e9 de d\u00e9couvrir la foi, de s\u2019interroger sur leur vie, de vivre ensemble dans les rencontres et les camps dans le respect de chacun et en tissant des liens d\u2019amiti\u00e9.<\/p>\n<p>Nous te disons merci pour les qualit\u00e9s de chacun\u00b7e, diff\u00e9rentes les unes des autres, qui font la richesse de leur groupe. Permets leur de pouvoir cultiver leurs dons et les offrir dans le travail qu\u2019ils font ensemble. Donne leur de former une communaut\u00e9 dans laquelle chacun \u00e0 sa place et se sente valoris\u00e9 pour qui il\/elle est.<\/p>\n<p>Puissent-ils\u00b7elles \u00eatre des t\u00e9moins de ton \u00c9vangile, source de libert\u00e9, de joie et d\u2019amour.<\/p>\n<p>Nous te prions pour que nous puissions comme paroisses \u00eatre un soutien pour l\u2019\u00e9quipe de l\u2019\u00c9toile, en leur offrant un mot d\u2019encouragement lorsqu\u2019elle en a besoin, un mot de gratitude tout au long de l\u2019ann\u00e9e pour leur travail. Amen<\/p>\n<p>A la fin des 3 ann\u00e9es de formation de moniteurs-trices de cat\u00e9chisme, c\u2019est un travail personnel qui est demand\u00e9 aux jeunes qui souhaitent obtenir leur dipl\u00f4me. Cette ann\u00e9e, ils sont trois \u00e0 l&rsquo;avoir obtenu. Merci et bravo \u00e0\u00a0 Aliz\u00e9e Rodriguez, Delphine Bucher et Robin Szabo.<\/p>\n<p>Nous te remercions, toi notre Dieu, des multiples ressources que tu fais na\u00eetre dans nos paroisses. Permet \u00e0 Aliz\u00e9e, Delphine et Robin et \u00e0 tous les moniteurs et monitrices d\u2019utiliser leurs dons au service de ton \u00c9glise et de notre soci\u00e9t\u00e9, en leur donnant la force et la joie dans leur travail.<\/p>\n<p>Que chacun d&rsquo;entre nous, \u00e0 sa mani\u00e8re, fasse rayonner ton \u00c9vangile. Qu&rsquo;en tant que paroisses, nous continuions \u00e0 soutenir les jeunes dans leurs r\u00e9flexions et leurs actions. Avec toute notre reconnaissance, \u00e0 toi et \u00e0 eux. Amen<\/p>\n<h2>Message: La loi du boomerang<\/h2>\n<p><em>Une jeune femme et un homme retrait\u00e9 arrivent \u00e0 l\u2019\u00e9glise, se croisent et s\u2019apostrophent.<\/em><\/p>\n<p><strong>Homme retrait\u00e9.<\/strong> Allons, jeune fille, croyez-vous vraiment que Dieu laissera impunies les fautes de ces adolescents qui s\u2019entassent par centaines dans des bo\u00eetes de nuit? D\u2019ailleurs ils ne viennent pas souvent au culte, et c\u2019est une grande faute d\u2019oublier Dieu! Pas \u00e9tonnant dans ces conditions que tant de jeunes attrapent ce virus!<\/p>\n<p><strong>Jeune femme.<\/strong> Et vous, qui faites partie des personnes \u00e0 risques\u2026 non seulement vous venez au culte, mais en plus vous prenez le bus sans mettre de masque, embrassez vos petits-enfants et jouez au scrabble avec tous vos amis! C\u2019est vous qui \u00eates irresponsable et offensez Dieu en mettant les autres et vous-m\u00eames en danger! Pas \u00e9tonnant, dans ces conditions, que tant de vieux soient contamin\u00e9s!<\/p>\n<p><em>Entre en proph\u00e8te de malheur.<\/em><\/p>\n<p><strong>Homme retrait\u00e9 et Jeune femme, en ch\u0153ur:<\/strong> Oh non, pas le proph\u00e8te de malheur!<\/p>\n<p><strong>Proph\u00e8te de malheur.<\/strong> Ainsi parle l\u2019\u00c9ternel : \u00ab Si vous ne m&rsquo;\u00e9coutez pas, si vous ne mettez pas en pratique tous mes commandements, [\u2026] voici comment moi je vous traiterai, je vous jetterai dans l&rsquo;\u00e9pouvante, avec le d\u00e9p\u00e9rissement et la fi\u00e8vre du Coronavirus [\u2026] \u00bb (L\u00e9vitique 26, 14 et 16)<\/p>\n<p><strong>Jeune Femme.<\/strong> Je ne me sens pas coupable de m\u2019amuser de temps \u00e0 autre en bo\u00eete, et d\u2019ailleurs je prends garde \u00e0 observer les mesures\u2026 pourquoi Dieu me punirait-il, moi, alors que je n\u2019ai rien fait de mal et me plie aux r\u00e8gles en vigueur? <em>En montrant l\u2019homme retrait\u00e9.<\/em> Alors que lui\u2026<\/p>\n<p><strong>Homme retrait\u00e9.<\/strong> Pourquoi me reprocherait-on de prendre le bus sans masque? N\u2019ai-je pas le droit de vivre? de profiter des jours qu\u2019il me reste? Je ne vois pas pourquoi je devrais passer mes derni\u00e8res ann\u00e9es \u00e0 souffrir de la solitude et de l\u2019isolement\u2026 <em>En montrant la jeune femme.<\/em> Alors qu\u2019elle\u2026<\/p>\n<p><strong>Homme retrait\u00e9 et Jeune femme, en ch\u0153ur.<\/strong> Le Corona ne me touchera pas\u2026 je n\u2019ai rien fait pour que Dieu me punisse!<\/p>\n<p><strong>Le Proph\u00e8te de malheur.<\/strong> <em>Rit et les menace.<\/em> \u00ab Voici ce que dit l\u2019\u00c9ternel: Je suis moi-m\u00eame en train de d\u00e9truire ce que j&rsquo;ai construit, je suis moi-m\u00eame en train d&rsquo;arracher ce que j&rsquo;ai plant\u00e9, partout dans ce pays. Et toi, tu aurais de grands projets pour toi-m\u00eame? N&rsquo;y pense plus, car je vais faire venir le malheur sur chacun, d\u00e9clare l\u2019\u00c9ternel\u00bb. (J\u00e9r\u00e9mie 45, 4-5)<\/p>\n<p><strong>Jeune Femme.<\/strong> Stop, tais-toi, je ne crois pas \u00e0 ce Dieu dont le projet serait de nous d\u00e9truire pour nos fautes. Je sais bien que beaucoup de personnes, m\u00eame les auteurs de la Bible, ont pens\u00e9 expliquer le mal comme une punition divine, mais je crois aussi que Dieu ne doit pas \u00eatre enferm\u00e9 dans cette image\u2026 Dieu est amour\u2026<\/p>\n<p><strong>Le proph\u00e8te de malheur.<\/strong> <em>Rit et r\u00e9plique.<\/em> Pourtant, tu viens de soutenir le contraire, tu viens de dire que certaines personnes m\u00e9ritaient d\u2019\u00eatre punies, que\u2026<\/p>\n<p><strong>Homme retrait\u00e9.<\/strong> Elle a raison, tais-toi. \u00c9coutons plut\u00f4t ce que nous dit l\u2019Evangile\u2026 J\u2019ai pens\u00e9 \u00e0 ce passage de Luc, au chapitre 13, qui me semble pouvoir\u2026 te clouer le bec!<br \/>\nJe vous lis ce passage: \u00ab\u00a0En ce temps-l\u00e0, quelques personnes vinrent raconter \u00e0 J\u00e9sus comment Pilate avait fait tuer des Galil\u00e9ens au moment o\u00f9 ils offraient des sacrifices \u00e0 Dieu\u2026\u00a0\u00bb<\/p>\n<p><strong>Le proph\u00e8te de malheur.<\/strong> Ah, ah, tu vois bien, c\u2019est comme ces personnes qui sont all\u00e9es prier \u00e0 Mulhouse\u2026 elles croyaient plaire \u00e0 Dieu par leur louange, mais Dieu les a punis!<\/p>\n<p><strong>Jeune Femme.<\/strong> Mais tu vas te taire, oui! Laisse-le continuer\u2026<\/p>\n<p><strong>Homme retrait\u00e9.<\/strong> <em>Reprend.<\/em> J\u00e9sus leur r\u00e9pondit : \u00ab Pensez-vous que si ces Galil\u00e9ens ont \u00e9t\u00e9 ainsi massacr\u00e9s, cela signifie qu&rsquo;ils \u00e9taient de plus grands p\u00e9cheurs que tous les autres Galil\u00e9ens? Non, vous dis-je\u2026 \u00bb<\/p>\n<p><strong>Jeune femme.<\/strong> <em>En regardant le proph\u00e8te de malheur.<\/em> Ah\u00a0! et toc\u00a0!<\/p>\n<p><strong>Homme retrait\u00e9.<\/strong> <em>Reprend.<\/em> \u00ab\u00a0Mais si vous ne vous convertissez pas, vous mourrez tous comme eux.\u00a0\u00bb<\/p>\n<p><strong>Proph\u00e8te de malheur.<\/strong> <em>En regardant la jeune femme.<\/em> Et toc toi-m\u00eame\u00a0!<\/p>\n<p><strong>Homme retrait\u00e9.<\/strong> Bon\u2026 me laisserez-vous lire jusqu\u2019\u00e0 la fin ? Je reprends:<br \/>\n\u00ab\u00a0Et ces dix-huit personnes que la tour de Silo\u00e9 a \u00e9cras\u00e9es en s&rsquo;\u00e9croulant, pensez-vous qu&rsquo;elles \u00e9taient plus coupables que tous les autres habitants de J\u00e9rusalem ?\u00a0\u00bb<\/p>\n<p><strong>Proph\u00e8te de malheur.<\/strong> Pas \u00e9tonnant\u2026 beaucoup de foyers ont \u00e9t\u00e9 constat\u00e9s dans les entreprises. Ce n\u2019est pas un hasard si \u00e7a touche le secteur du b\u00e2timent qui n\u2019a pas d\u00fb respecter le confinement et n\u2019a pas respect\u00e9 les directives sanitaires. (RTN du 17 mars\u2026)<\/p>\n<p><strong>Homme retrait\u00e9.<\/strong> <em>Soupire et reprend.<\/em> J\u00e9sus leur r\u00e9pond : \u00ab Non, vous dis-je; mais si vous ne vous convertissez pas, vous mourrez tous comme eux. \u00bb<\/p>\n<p><em>Temps de silence. Jeune Femme et Proph\u00e8te de malheur r\u00e9fl\u00e9chissent \u00e0 ce qu&rsquo;ils viennent d&rsquo;entendre.<br \/>\n<\/em><\/p>\n<p><strong>Jeune Femme.<\/strong> Attends\u2026 Relis-moi encore une fois tout ce passage. Au proph\u00e8te\u00a0: Et toi, ne l\u2019interromps pas\u00a0!<\/p>\n<p><strong>Homme retrait\u00e9.<\/strong> \u00ab En ce temps-l\u00e0, quelques personnes vinrent raconter \u00e0 J\u00e9sus comment Pilate avait fait tuer des Galil\u00e9ens au moment o\u00f9 ils offraient des sacrifices \u00e0 Dieu. J\u00e9sus leur r\u00e9pondit : \u00ab Pensez-vous que si ces Galil\u00e9ens ont \u00e9t\u00e9 ainsi massacr\u00e9s, cela signifie qu&rsquo;ils \u00e9taient de plus grands p\u00e9cheurs que tous les autres Galil\u00e9ens? Non, vous dis-je, mais si vous ne vous convertissez pas, vous mourrez tous comme eux. Et ces dix-huit personnes que la tour de Silo\u00e9 a \u00e9cras\u00e9es en s&rsquo;\u00e9croulant, pensez-vous qu&rsquo;elles \u00e9taient plus coupables que tous les autres habitants de J\u00e9rusalem? Non, vous dis-je ; mais si vous ne vous convertissez pas, vous mourrez tous comme eux. \u00bb<\/p>\n<p><strong>Jeune Femme.<\/strong> D\u2019accord\u2026 ce n\u2019est pas de leur faute si la tour s\u2019est effondr\u00e9e sur eux, ils n\u2019\u00e9taient pas plus coupables que d\u2019autres. Pas plus innocents non plus. C\u2019est ainsi! Mais alors pourquoi certaines personnes, peut-\u00eatre nous, vont mourir comme \u00e7a, sans raison, si on ne se convertit pas??? Qu\u2019est-ce que cela veut dire? Que si on ne croit pas en Dieu de la bonne mani\u00e8re, on chopera le Coronavirus?<\/p>\n<p><strong>Homme retrait\u00e9.<\/strong> C\u2019est vrai, J\u00e9sus n\u2019explique pas la raison de leur malheur, il les excuse\u2026 mais en m\u00eame temps, il menace tout le monde de subir le m\u00eame sort\u00a0!<\/p>\n<p><strong>Proph\u00e8te de malheur.<\/strong> H\u00e9 h\u00e9 h\u00e9\u2026 <em>Se frotte les mains.<\/em><\/p>\n<p><strong>Jeune Femme.<\/strong> Toi, tu ne t\u2019en tireras pas \u00e0 si bon compte\u2026 Reprenons les choses. Le plus important, c\u2019est que J\u00e9sus dit bien que le malheur n\u2019a aucun rapport avec les fautes ou les erreurs qu\u2019on peut commettre. Les ouvriers \u00e0 Silo\u00e9 n\u2019ont rien fait de pire que les autres habitants de J\u00e9rusalem\u2026<\/p>\n<p><strong>Homme retrait\u00e9.<\/strong> C\u2019est vrai. Le probl\u00e8me, c\u2019est qu\u2019on les accuse\u2026 on pense forc\u00e9ment qu\u2019ils sont coupables\u2026 parce qu\u2019on pr\u00e9f\u00e8re toujours avoir une explication du malheur qui arrive\u2026<\/p>\n<p><strong>Jeune femme.<\/strong> Oui\u2026 par exemple en disant que les jeunes sont responsables du Corona\u2026<\/p>\n<p><strong>Homme retrait\u00e9.<\/strong> Ou que les vieux sont coupables de la pand\u00e9mie\u2026<\/p>\n<p><strong>Jeune femme.<\/strong> C\u2019est vrai qu\u2019on arrive nulle part comme \u00e7a\u2026 Laissons donc la question de la responsabilit\u00e9 de c\u00f4t\u00e9\u2026 cessons de nous culpabiliser\u2026<\/p>\n<p><strong>Homme retrait\u00e9.<\/strong> J\u2019ai compris\u00a0! si on cherche toujours un coupable\u2026 alors forc\u00e9ment, d\u00e8s qu\u2019un malheur nous arrive, nous devons consid\u00e9rer que nous l\u2019avons m\u00e9rit\u00e9. Au premier malheur qui nous arrivera, nous nous accablerons de reproches\u00a0! Et cela nous emp\u00eachera de vivre\u00a0! C\u2019est \u00e7a que J\u00e9sus veut dire quand il dit \u00ab\u00a0vous mourrez tous de m\u00eame si vous pensez ainsi\u00a0\u00bb.<\/p>\n<p><strong>Jeune femme.<\/strong> Tu as raison. J\u2019ai bien l\u2019impression que J\u00e9sus nous invite \u00e0 changer de regard, c\u2019est cela que signifie le mot \u00ab\u00a0conversion\u00a0\u00bb. Il faut accepter qu\u2019on ne comprend pas toujours l\u2019origine du mal, et plut\u00f4t que de s\u2019accuser les uns les autres, il faut chercher \u00e0 faire face ensemble aux malheurs qui nous tombent dessus\u00a0: c\u2019est la diff\u00e9rence entre culpabilit\u00e9 et responsabilit\u00e9\u00a0!<\/p>\n<p><strong>Proph\u00e8te de malheur.<\/strong> Se grattant le menton. C\u2019est que \u00e7a devient int\u00e9ressant tout \u00e7a\u2026 Changer de regard, changer de mode de pens\u00e9e, changer de direction\u2026 Cela m\u2019inspire\u00a0!<\/p>\n<p><strong>Homme retrait\u00e9.<\/strong> S\u2019adressant au proph\u00e8te de malheur. Et si tu as envie de changer de direction, sans savoir quel chemin prendre, sache que J\u00e9sus dans les \u00e9vangiles propose plusieurs voies toutes plus int\u00e9ressantes les unes que les autres\u2026<\/p>\n<p><strong>Proph\u00e8te de malheur.<\/strong> Ta ta ta\u2026 je n\u2019ai plus l\u2019\u00e2ge pour m\u2019inscrire au KT, mais par contre, je peux vous livrer un dernier oracle de l\u2019\u00c9ternel. Il prend une grande inspiration.\u00a0 \u00ab Pensez-vous que j&rsquo;aime voir mourir les m\u00e9chants? Je vous le d\u00e9clare, moi, le Seigneur Dieu, tout ce que je d\u00e9sire, c&rsquo;est qu&rsquo;ils changent de conduite et qu&rsquo;ils vivent \u00bb. (Ezechiel 18, 23)<\/p>\n<p><strong>Jeune femme.<\/strong> Oui, la logique de la culpabilit\u00e9, c\u2019est comme un boomerang\u00a0: tu l\u2019envoies sur les autres, et il te revient en pleine poire\u00a0! Il faut donc se convertir, changer de regard\u00a0!<\/p>\n<p><strong>Homme retrait\u00e9.<\/strong> Oui, par exemple, choisir la logique de l\u2019amour qui est aussi comme un boomerang\u2026 tu l\u2019envoies autour de toi, et il te revient de toutes parts\u00a0!<\/p>\n<p><strong>Proph\u00e8te de malheur.<\/strong> Amen!<\/p>\n<h2>Accueil des cat\u00e9chum\u00e8nes<\/h2>\n<p>Cette ann\u00e9e, 20 jeunes ont choisi de commencer cette aventure de la d\u00e9couverte de la foi chr\u00e9tienne protestante r\u00e9form\u00e9e. Nous voulons les accueillir maintenant et leur offrir un mot de b\u00e9n\u00e9diction.<\/p>\n<p>Chers cat\u00e9chum\u00e8nes, nous nous r\u00e9jouissons beaucoup de vous accompagner sur le chemin de la d\u00e9couverte de la foi chr\u00e9tienne. Ensemble cette ann\u00e9e, nous voulons prendre le temps de nous interroger sur Dieu, sur nous-m\u00eames, sur la vie. Ensemble nous voulons cr\u00e9er un espace pour \u00e9couter et exp\u00e9rimenter la mani\u00e8re de comprendre le monde que nous offre l\u2019\u00c9vangile. Ensemble nous ferons de la place \u00e0 la joie et au rire dans les rencontres et les camps.<\/p>\n<p>Vous avez entendu aujourd\u2019hui l\u2019invitation \u00e0 changer de regard sur le monde. A sortir de la vision dualiste o\u00f9 s\u2019opposent et s\u2019accusent ceux qui pensent avoir raison et ceux qui semblent avoir tort. A passer de la logique du jugement et de la culpabilit\u00e9 \u00e0 la logique de l\u2019amour. Voil\u00e0 ce que nous allons essayer de vivre ensemble cette ann\u00e9e au KT.<\/p>\n<p>Symboliquement, nous aimerions vous offrir un boomerang. Ce que vous lancez autour de vous vous revient. Si vous lancez des jugements \u00e0 l\u2019emporte pi\u00e8ce, si vous lancez de la haine et du m\u00e9pris, votre propre vie en sera amoch\u00e9e. Vous aurez beau vous recroqueviller sur vous-m\u00eames pour vous en prot\u00e9ger, vous ne pourrez pas \u00e9viter d\u2019en \u00eatre atteints. Ce \u00e0 quoi nous appelle l\u2019\u00c9vangile, c\u2019est \u00e0 lancer autour de nous ce qui fait vivre. L\u2019amour, l\u2019amiti\u00e9, la bienveillance. Lancez dans une intention bonne. Ce qui vous reviendra sera bon et r\u00e9parateur. Et saisissez ce qui vous est donn\u00e9. Les signes de vie, de joie, de bont\u00e9. Et que Dieu vous couvre de b\u00e9n\u00e9dictions !<\/p>\n<p>Que Dieu vous accompagne dans votre parcours de cat\u00e9chisme et dans vos explorations!<br \/>\nPuissiez-vous lancer ce qui donne \u00e0 vivre et saisir les b\u00e9n\u00e9dictions qui vous sont donn\u00e9es!<br \/>\nAmen.<\/p>\n<h2>Pri\u00e8re d&rsquo;intercession<\/h2>\n<p>Notre Dieu, toi qui as cr\u00e9\u00e9 les cieux et la terre,<br \/>\nSois aux c\u00f4t\u00e9s de notre plan\u00e8te, de sa v\u00e9g\u00e9tation, de ses animaux, de son \u00e9cosyst\u00e8me.<br \/>\nDonne aux humains le courage de prendre des mesures pour cesser de les mettre en danger, et restaure l\u2019\u00e9quilibre de ta cr\u00e9ation.<\/p>\n<p>Notre Dieu, toi qui nous donnes la vie et nous prot\u00e8ge,<br \/>\nSois aux c\u00f4t\u00e9s de celles et ceux qui souffrent de la pr\u00e9carit\u00e9, de la maladie, de celles et ceux qui sont victimes de la guerre et forc\u00e9-es \u00e0 l\u2019exil.<br \/>\nDonne-leur ta lumi\u00e8re, sois pour eux un refuge et une source de r\u00e9g\u00e9n\u00e9ration.<\/p>\n<p>Notre Dieu, toi qui en J\u00e9sus-Christ nous invites \u00e0 l\u2019amour du prochain,<br \/>\nSois aux c\u00f4t\u00e9s des minorit\u00e9s stigmatis\u00e9es, des \u00e9trangers mis de c\u00f4t\u00e9, des personnes isol\u00e9es.<br \/>\nDonne-leur de rencontrer sur leur chemin des personnes, nous peut-\u00eatre, qui les accueillent et leur offrent du soutien.<\/p>\n<p>Notre Dieu, toi qui en J\u00e9sus-Christ nous accueilles inconditionnellement,<br \/>\nSois aux c\u00f4t\u00e9s des cat\u00e9chum\u00e8nes de La BARC et du Joran dans chaque moment de leur vie.<br \/>\nDonne-leur de vivre pleinement des temps de partage et d\u2019amiti\u00e9 qui soient source d\u2019\u00e9panouissement.<\/p>\n<p>Notre Dieu, toi dont l\u2019Esprit nous met en route vers de nouveaux horizons,<br \/>\nSois aux c\u00f4t\u00e9s des monitrices et moniteurs dans chaque moment de leur vie.<br \/>\nDonne-leur particuli\u00e8rement les ressources et la cr\u00e9ativit\u00e9 n\u00e9cessaires \u00e0 leur accompagnement des cat\u00e9chum\u00e8nes et dans toutes leurs activit\u00e9s personnelles.<\/p>\n<p>Notre Dieu, toi que nous ne pouvons enfermer dans nos repr\u00e9sentations,<br \/>\nChemine avec nous chaque jour, toi qui t\u2019es approch\u00e9 de nous en J\u00e9sus-Christ,<br \/>\nDonne-nous ton Esprit, qu\u2019il souffle sur nos vies et nous inspire l\u2019amour, la justice et la paix.<\/p>\n<p>Et ensemble nous t\u2019adressons la pri\u00e8re que J\u00e9sus nous a enseign\u00e9e:<br \/>\nNotre P\u00e8re qui es aux cieux<br \/>\nque ton nom soit sanctifi\u00e9,<br \/>\nque ton r\u00e8gne vienne,<br \/>\nque ta volont\u00e9 soit faite sur la terre comme au ciel.<br \/>\nDonne-nous aujourd\u2019hui notre pain de ce jour.<br \/>\nPardonne-nous nos offenses,<br \/>\ncomme nous pardonnons aussi \u00e0 ceux qui nous ont offens\u00e9s.<br \/>\nEt ne nous laisse pas entrer en tentation<br \/>\nmais d\u00e9livre-nous du Mal.<br \/>\nCar c\u2019est \u00e0 toi qu\u2019appartiennent<br \/>\nLe r\u00e8gne, la puissance et la gloire<br \/>\nAux si\u00e8cles des si\u00e8cles<br \/>\nAmen<\/p>\n<h2>B\u00e9n\u00e9diction<\/h2>\n<p>Dans le quotidien de notre monde et de notre vie, que nous puissions lancer des signes de vie pour autres, pour le monde et pour nous-m\u00eames!<br \/>\nDieu nous en donne la force, lui dont l\u2019amour ne s\u2019\u00e9puisera jamais.<br \/>\nLui dont la bont\u00e9 jamais ne se d\u00e9mentira.<\/p>\n<p>Que l\u2019amour de Dieu nous entoure<br \/>\nQue la force de Dieu nous soutienne<br \/>\net que la paix de Dieu emplisse nos c\u0153urs.<\/p>\n<p>Amen<\/p>\n<hr \/>\n<p>Illustration: <a href=\"https:\/\/www.flickr.com\/photos\/rajitharanasinghe\/33763073420\/in\/photolist-Trwzrw-SytJUW-ernu1-7dV1zd-2iCWA1n-XSu9Fx-2dWTuNv-JVU2cd-SixyCe-24JczVX-24UUsgy-5SreqZ-2kZFt1-4ef7V9-8NFXA1-4ZPvLF-oZqRZX-jL2BjF-9iJAbq-2iWWz6F-9iFsKz-7YM3Te-2dWTuUc-27EGrNV-6L5nsq-27EGyqH-hM5GKX-pvcSVK-27EGw2V-5GgoSt-nvNMNi-nk22fX-nmMxbx-r7ofL2-bx1iUr-ikZidB-9brJUR-2apQyWM-9baSmV-wz9wb-TExo7d-23pp2Dv-emMbmK-dcEj2Y-x56hHM-nLfViE-jZQMcM-nvPh9f-KVjHgJ-nN9eEs\">Rajitha Ranasinghe<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Culte d&rsquo;accueil des nouveaux cat\u00e9chum\u00e8nes et reconnaissance pour les jeunes moniteurs\u00b7trices des paroisses de La BARC et du Joran. Par Antoine Staffelbach, Manon Schneider, Olivier Junod, C\u00e9cile Guinand, Sarah Badertscher et Diane Friedli. Accueil M\u00eame si les collines venaient \u00e0 s&rsquo;\u00e9branler, m\u00eame si les montagnes venaient \u00e0 changer de place, l&rsquo;amour que j&rsquo;ai pour toi &hellip; <a href=\"https:\/\/www.eren.ch\/barc\/2020\/10\/25\/la-loi-du-boomerang\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;La loi du boomerang&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":15,"featured_media":2248,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2204],"tags":[],"class_list":["post-2245","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.6 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>La loi du boomerang &#8226; Paroisse r\u00e9form\u00e9e de La BARC<\/title>\n<meta name=\"description\" content=\"Culte d&#039;accueil des nouveaux cat\u00e9chum\u00e8nes et reconnaissance pour les jeunes moniteurs\u00b7trices des paroisses de La BARC et du Joran.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eren.ch\/barc\/2020\/10\/25\/la-loi-du-boomerang\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La loi du boomerang\" \/>\n<meta property=\"og:description\" content=\"Culte d&#039;accueil des nouveaux cat\u00e9chum\u00e8nes et reconnaissance pour les jeunes moniteurs\u00b7trices des paroisses de La BARC et du Joran.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eren.ch\/barc\/2020\/10\/25\/la-loi-du-boomerang\/\" \/>\n<meta property=\"og:site_name\" content=\"Paroisse r\u00e9form\u00e9e de La BARC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eglise.EREN\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/diane.friedli\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-25T12:55:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-27T09:30:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2020\/10\/boomerang.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2047\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diane Friedli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@egliseeren\" \/>\n<meta name=\"twitter:site\" content=\"@egliseeren\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diane Friedli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2020\\\/10\\\/25\\\/la-loi-du-boomerang\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2020\\\/10\\\/25\\\/la-loi-du-boomerang\\\/\"},\"author\":{\"name\":\"Diane Friedli\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/#\\\/schema\\\/person\\\/4cbf919d165245f3c00615964603c95e\"},\"headline\":\"La loi du boomerang\",\"datePublished\":\"2020-10-25T12:55:41+00:00\",\"dateModified\":\"2020-10-27T09:30:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2020\\\/10\\\/25\\\/la-loi-du-boomerang\\\/\"},\"wordCount\":3316,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2020\\\/10\\\/25\\\/la-loi-du-boomerang\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/10\\\/boomerang.jpg\",\"articleSection\":[\"Cultes et pr\u00e9dications\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2020\\\/10\\\/25\\\/la-loi-du-boomerang\\\/\",\"url\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2020\\\/10\\\/25\\\/la-loi-du-boomerang\\\/\",\"name\":\"La loi du boomerang &#8226; Paroisse r\u00e9form\u00e9e de La BARC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2020\\\/10\\\/25\\\/la-loi-du-boomerang\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2020\\\/10\\\/25\\\/la-loi-du-boomerang\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/10\\\/boomerang.jpg\",\"datePublished\":\"2020-10-25T12:55:41+00:00\",\"dateModified\":\"2020-10-27T09:30:37+00:00\",\"description\":\"Culte d'accueil des nouveaux cat\u00e9chum\u00e8nes et reconnaissance pour les jeunes moniteurs\u00b7trices des paroisses de La BARC et du Joran.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2020\\\/10\\\/25\\\/la-loi-du-boomerang\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2020\\\/10\\\/25\\\/la-loi-du-boomerang\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2020\\\/10\\\/25\\\/la-loi-du-boomerang\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/10\\\/boomerang.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/10\\\/boomerang.jpg\",\"width\":2047,\"height\":1365},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2020\\\/10\\\/25\\\/la-loi-du-boomerang\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La loi du boomerang\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/#website\",\"url\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/\",\"name\":\"Paroisse r\u00e9form\u00e9e de La BARC\",\"description\":\"B\u00f4le - Auvernier - Rochefort - Colombier\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/#organization\",\"name\":\"Paroisse de La BARC\",\"url\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/12\\\/logo-barc.png\",\"contentUrl\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/12\\\/logo-barc.png\",\"width\":240,\"height\":117,\"caption\":\"Paroisse de La BARC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eglise.EREN\",\"https:\\\/\\\/x.com\\\/egliseeren\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/\u00c9glise_r\u00e9form\u00e9e_\u00e9vang\u00e9lique_du_canton_de_Neuch\u00e2tel\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/#\\\/schema\\\/person\\\/4cbf919d165245f3c00615964603c95e\",\"name\":\"Diane Friedli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4174ee343655321c9dbd4d2c6ee9c77ede314be9a69b089058a09978eeae611?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4174ee343655321c9dbd4d2c6ee9c77ede314be9a69b089058a09978eeae611?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4174ee343655321c9dbd4d2c6ee9c77ede314be9a69b089058a09978eeae611?s=96&d=blank&r=g\",\"caption\":\"Diane Friedli\"},\"sameAs\":[\"https:\\\/\\\/dianefriedli.ch\\\/\",\"https:\\\/\\\/www.facebook.com\\\/diane.friedli\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCNrNBZYbsUHnqKGrrw3JSfw\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/\u00c9glise_r\u00e9form\u00e9e_\u00e9vanglique_du_canton_de_Neuch\u00e2tel\"],\"honorificPrefix\":\"Mme\",\"birthDate\":\"1980-10-28\",\"gender\":\"femme\",\"knowsAbout\":[\"th\u00e9ologie\",\"cat\u00e9ch\u00e8se\",\"vulgarisation th\u00e9ologique\",\"pr\u00e9dication\"],\"knowsLanguage\":[\"fran\u00e7ais\",\"allemand\",\"anglais\"],\"jobTitle\":\"pasteure\",\"worksFor\":\"EREN\",\"url\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/author\\\/dfriedli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"La loi du boomerang &#8226; Paroisse r\u00e9form\u00e9e de La BARC","description":"Culte d'accueil des nouveaux cat\u00e9chum\u00e8nes et reconnaissance pour les jeunes moniteurs\u00b7trices des paroisses de La BARC et du Joran.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eren.ch\/barc\/2020\/10\/25\/la-loi-du-boomerang\/","og_locale":"fr_FR","og_type":"article","og_title":"La loi du boomerang","og_description":"Culte d'accueil des nouveaux cat\u00e9chum\u00e8nes et reconnaissance pour les jeunes moniteurs\u00b7trices des paroisses de La BARC et du Joran.","og_url":"https:\/\/www.eren.ch\/barc\/2020\/10\/25\/la-loi-du-boomerang\/","og_site_name":"Paroisse r\u00e9form\u00e9e de La BARC","article_publisher":"https:\/\/www.facebook.com\/eglise.EREN","article_author":"https:\/\/www.facebook.com\/diane.friedli","article_published_time":"2020-10-25T12:55:41+00:00","article_modified_time":"2020-10-27T09:30:37+00:00","og_image":[{"width":2047,"height":1365,"url":"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2020\/10\/boomerang.jpg","type":"image\/jpeg"}],"author":"Diane Friedli","twitter_card":"summary_large_image","twitter_creator":"@egliseeren","twitter_site":"@egliseeren","twitter_misc":{"\u00c9crit par":"Diane Friedli","Dur\u00e9e de lecture estim\u00e9e":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eren.ch\/barc\/2020\/10\/25\/la-loi-du-boomerang\/#article","isPartOf":{"@id":"https:\/\/www.eren.ch\/barc\/2020\/10\/25\/la-loi-du-boomerang\/"},"author":{"name":"Diane Friedli","@id":"https:\/\/www.eren.ch\/barc\/#\/schema\/person\/4cbf919d165245f3c00615964603c95e"},"headline":"La loi du boomerang","datePublished":"2020-10-25T12:55:41+00:00","dateModified":"2020-10-27T09:30:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eren.ch\/barc\/2020\/10\/25\/la-loi-du-boomerang\/"},"wordCount":3316,"publisher":{"@id":"https:\/\/www.eren.ch\/barc\/#organization"},"image":{"@id":"https:\/\/www.eren.ch\/barc\/2020\/10\/25\/la-loi-du-boomerang\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2020\/10\/boomerang.jpg","articleSection":["Cultes et pr\u00e9dications"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eren.ch\/barc\/2020\/10\/25\/la-loi-du-boomerang\/","url":"https:\/\/www.eren.ch\/barc\/2020\/10\/25\/la-loi-du-boomerang\/","name":"La loi du boomerang &#8226; Paroisse r\u00e9form\u00e9e de La BARC","isPartOf":{"@id":"https:\/\/www.eren.ch\/barc\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eren.ch\/barc\/2020\/10\/25\/la-loi-du-boomerang\/#primaryimage"},"image":{"@id":"https:\/\/www.eren.ch\/barc\/2020\/10\/25\/la-loi-du-boomerang\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2020\/10\/boomerang.jpg","datePublished":"2020-10-25T12:55:41+00:00","dateModified":"2020-10-27T09:30:37+00:00","description":"Culte d'accueil des nouveaux cat\u00e9chum\u00e8nes et reconnaissance pour les jeunes moniteurs\u00b7trices des paroisses de La BARC et du Joran.","breadcrumb":{"@id":"https:\/\/www.eren.ch\/barc\/2020\/10\/25\/la-loi-du-boomerang\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eren.ch\/barc\/2020\/10\/25\/la-loi-du-boomerang\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eren.ch\/barc\/2020\/10\/25\/la-loi-du-boomerang\/#primaryimage","url":"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2020\/10\/boomerang.jpg","contentUrl":"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2020\/10\/boomerang.jpg","width":2047,"height":1365},{"@type":"BreadcrumbList","@id":"https:\/\/www.eren.ch\/barc\/2020\/10\/25\/la-loi-du-boomerang\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.eren.ch\/barc\/"},{"@type":"ListItem","position":2,"name":"La loi du boomerang"}]},{"@type":"WebSite","@id":"https:\/\/www.eren.ch\/barc\/#website","url":"https:\/\/www.eren.ch\/barc\/","name":"Paroisse r\u00e9form\u00e9e de La BARC","description":"B\u00f4le - Auvernier - Rochefort - Colombier","publisher":{"@id":"https:\/\/www.eren.ch\/barc\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eren.ch\/barc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.eren.ch\/barc\/#organization","name":"Paroisse de La BARC","url":"https:\/\/www.eren.ch\/barc\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eren.ch\/barc\/#\/schema\/logo\/image\/","url":"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2020\/12\/logo-barc.png","contentUrl":"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2020\/12\/logo-barc.png","width":240,"height":117,"caption":"Paroisse de La BARC"},"image":{"@id":"https:\/\/www.eren.ch\/barc\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eglise.EREN","https:\/\/x.com\/egliseeren","https:\/\/fr.wikipedia.org\/wiki\/\u00c9glise_r\u00e9form\u00e9e_\u00e9vang\u00e9lique_du_canton_de_Neuch\u00e2tel"]},{"@type":"Person","@id":"https:\/\/www.eren.ch\/barc\/#\/schema\/person\/4cbf919d165245f3c00615964603c95e","name":"Diane Friedli","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f4174ee343655321c9dbd4d2c6ee9c77ede314be9a69b089058a09978eeae611?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f4174ee343655321c9dbd4d2c6ee9c77ede314be9a69b089058a09978eeae611?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f4174ee343655321c9dbd4d2c6ee9c77ede314be9a69b089058a09978eeae611?s=96&d=blank&r=g","caption":"Diane Friedli"},"sameAs":["https:\/\/dianefriedli.ch\/","https:\/\/www.facebook.com\/diane.friedli","https:\/\/www.youtube.com\/channel\/UCNrNBZYbsUHnqKGrrw3JSfw","https:\/\/fr.wikipedia.org\/wiki\/\u00c9glise_r\u00e9form\u00e9e_\u00e9vanglique_du_canton_de_Neuch\u00e2tel"],"honorificPrefix":"Mme","birthDate":"1980-10-28","gender":"femme","knowsAbout":["th\u00e9ologie","cat\u00e9ch\u00e8se","vulgarisation th\u00e9ologique","pr\u00e9dication"],"knowsLanguage":["fran\u00e7ais","allemand","anglais"],"jobTitle":"pasteure","worksFor":"EREN","url":"https:\/\/www.eren.ch\/barc\/author\/dfriedli\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/posts\/2245","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/comments?post=2245"}],"version-history":[{"count":3,"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/posts\/2245\/revisions"}],"predecessor-version":[{"id":2250,"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/posts\/2245\/revisions\/2250"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/media\/2248"}],"wp:attachment":[{"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/media?parent=2245"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/categories?post=2245"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/tags?post=2245"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}