{"id":3636,"date":"2022-05-10T06:17:57","date_gmt":"2022-05-10T04:17:57","guid":{"rendered":"https:\/\/www.eren.ch\/barc\/?p=3636"},"modified":"2022-05-11T15:06:04","modified_gmt":"2022-05-11T13:06:04","slug":"sandwich-au-feminin","status":"publish","type":"post","link":"https:\/\/www.eren.ch\/barc\/2022\/05\/10\/sandwich-au-feminin\/","title":{"rendered":"Sandwich au f\u00e9minin"},"content":{"rendered":"<p>Deux r\u00e9cits, deux femmes.<br \/>\nDans l&rsquo;Evangile de Marc, elles sont au centre d&rsquo;un dispositif litt\u00e9raire appel\u00e9 \u00ab\u00a0sandwich\u00a0\u00bb.\u00a0 Cela nous apprend comment J\u00e9sus gu\u00e9rit.<\/p>\n<blockquote><p>Marc 5<\/p>\n<div class=\"bloc_verset\">\n<div class=\"bloc_verset\"><span class=\"verset v21\"><a href=\"https:\/\/lire.la-bible.net\/verset\/Marc\/5\/21\/NBS\"><span class=\"reference\">21<\/span><\/a>J\u00e9sus regagna l&rsquo;autre rive en bateau, et une grande foule se rassembla aupr\u00e8s de lui. Il \u00e9tait au bord de la mer.\u00a0<\/span><\/div>\n<div class=\"bloc_verset\"><span class=\"verset v22\"><a href=\"https:\/\/lire.la-bible.net\/verset\/Marc\/5\/22\/NBS\"><span class=\"reference\">22<\/span><\/a>Un des chefs de la synagogue, nomm\u00e9 Ja\u00efros, arrive ; le voyant, il tombe \u00e0 ses pieds\u00a0<\/span><\/div>\n<div class=\"bloc_verset\"><span class=\"verset v23\"><a href=\"https:\/\/lire.la-bible.net\/verset\/Marc\/5\/23\/NBS\"><span class=\"reference\">23<\/span><\/a>et le supplie instamment : Ma fille est sur le point de mourir ; viens, impose-lui les mains, afin qu&rsquo;elle soit sauv\u00e9e et qu&rsquo;elle vive.\u00a0<\/span><\/div>\n<div class=\"bloc_verset\"><span class=\"verset v24\"><a href=\"https:\/\/lire.la-bible.net\/verset\/Marc\/5\/24\/NBS\"><span class=\"reference\">24<\/span><\/a>Il s&rsquo;en alla avec lui. Une grande foule le suivait et le pressait de toutes parts.<\/span><\/p>\n<div class=\"verset_btn\"><\/div>\n<\/div>\n<div class=\"bloc_verset\"><span class=\"verset v25\"><a href=\"https:\/\/lire.la-bible.net\/verset\/Marc\/5\/25\/NBS\"><span class=\"reference\">25<\/span><\/a>Or il y avait l\u00e0 une femme atteinte d&rsquo;une perte de sang depuis douze ans.\u00a0<\/span><\/div>\n<div class=\"bloc_verset\"><span class=\"verset v26\"><a href=\"https:\/\/lire.la-bible.net\/verset\/Marc\/5\/26\/NBS\"><span class=\"reference\">26<\/span><\/a>Elle avait beaucoup souffert du fait de nombreux m\u00e9decins, et elle avait d\u00e9pens\u00e9 tout ce qu&rsquo;elle poss\u00e9dait sans en tirer aucun avantage ; au contraire, son \u00e9tat avait plut\u00f4t empir\u00e9.\u00a0<\/span><\/div>\n<div class=\"bloc_verset\"><span class=\"verset v27\"><a href=\"https:\/\/lire.la-bible.net\/verset\/Marc\/5\/27\/NBS\"><span class=\"reference\">27<\/span><\/a>Ayant entendu parler de J\u00e9sus, elle vint dans la foule, par-derri\u00e8re, et toucha son v\u00eatement.\u00a0<\/span><\/div>\n<div class=\"bloc_verset\"><span class=\"verset v28\"><a href=\"https:\/\/lire.la-bible.net\/verset\/Marc\/5\/28\/NBS\"><span class=\"reference\">28<\/span><\/a>Car elle disait : Si je touche ne serait-ce que ses v\u00eatements, je serai sauv\u00e9e !\u00a0<\/span><\/div>\n<div class=\"bloc_verset\"><span class=\"verset v29\"><a href=\"https:\/\/lire.la-bible.net\/verset\/Marc\/5\/29\/NBS\"><span class=\"reference\">29<\/span><\/a>Aussit\u00f4t sa perte de sang s&rsquo;arr\u00eata, et elle sut, dans son corps, qu&rsquo;elle \u00e9tait gu\u00e9rie de son mal.<\/span><\/div>\n<div class=\"bloc_verset\"><span class=\"verset v30\"><a href=\"https:\/\/lire.la-bible.net\/verset\/Marc\/5\/30\/NBS\"><span class=\"reference\">30<\/span><\/a>J\u00e9sus sut aussit\u00f4t, en lui-m\u00eame, qu&rsquo;une force \u00e9tait sortie de lui. Il se retourna dans la foule et se mit \u00e0 dire : Qui a touch\u00e9 mes v\u00eatements ?\u00a0<\/span><\/div>\n<div class=\"bloc_verset\"><span class=\"verset v31\"><a href=\"https:\/\/lire.la-bible.net\/verset\/Marc\/5\/31\/NBS\"><span class=\"reference\">31<\/span><\/a>Ses disciples lui disaient : Tu vois la foule qui te presse de toutes parts, et tu dis : \u00ab Qui m&rsquo;a touch\u00e9 ? \u00bb\u00a0<\/span><\/div>\n<div class=\"bloc_verset\"><span class=\"verset v32\"><a href=\"https:\/\/lire.la-bible.net\/verset\/Marc\/5\/32\/NBS\"><span class=\"reference\">32<\/span><\/a>Mais il regardait autour de lui pour voir celle qui avait fait cela.\u00a0<\/span><\/div>\n<div class=\"bloc_verset\"><span class=\"verset v33\"><a href=\"https:\/\/lire.la-bible.net\/verset\/Marc\/5\/33\/NBS\"><span class=\"reference\">33<\/span><\/a>Sachant ce qui lui \u00e9tait arriv\u00e9, la femme, tremblant de peur, vint se jeter \u00e0 ses pieds et lui dit toute la v\u00e9rit\u00e9.\u00a0<\/span><\/div>\n<div class=\"bloc_verset\"><span class=\"verset v34\"><a href=\"https:\/\/lire.la-bible.net\/verset\/Marc\/5\/34\/NBS\"><span class=\"reference\">34<\/span><\/a>Mais il lui dit\u00a0: Ma fille, ta foi t&rsquo;a sauv\u00e9e\u00a0; va en paix et sois gu\u00e9rie de ton mal.<\/span><\/p>\n<div class=\"verset_btn\"><\/div>\n<\/div>\n<div class=\"bloc_verset\"><span class=\"verset v35\"><a href=\"https:\/\/lire.la-bible.net\/verset\/Marc\/5\/35\/NBS\"><span class=\"reference\">35<\/span><\/a>Il parlait encore lorsque arrivent de chez le chef de la synagogue des gens qui disent : Ta fille est morte ; pourquoi importuner encore le ma\u00eetre ?\u00a0<\/span><\/div>\n<div class=\"bloc_verset\"><span class=\"verset v36\"><a href=\"https:\/\/lire.la-bible.net\/verset\/Marc\/5\/36\/NBS\"><span class=\"reference\">36<\/span><\/a>Mais J\u00e9sus, qui avait surpris ces paroles, dit au chef de la synagogue : N&rsquo;aie pas peur, crois seulement.\u00a0<\/span><\/div>\n<div class=\"bloc_verset\"><span class=\"verset v37\"><a href=\"https:\/\/lire.la-bible.net\/verset\/Marc\/5\/37\/NBS\"><span class=\"reference\">37<\/span><\/a>Et il ne laissa personne l&rsquo;accompagner, si ce n&rsquo;est Pierre, Jacques et Jean, fr\u00e8re de Jacques.\u00a0<\/span><\/div>\n<div class=\"bloc_verset\"><span class=\"verset v38\"><a href=\"https:\/\/lire.la-bible.net\/verset\/Marc\/5\/38\/NBS\"><span class=\"reference\">38<\/span><\/a>Ils arrivent chez le chef de la synagogue ; l\u00e0 il voit de l&rsquo;agitation, des gens qui pleurent et qui poussent de grands cris.\u00a0<\/span><\/div>\n<div class=\"bloc_verset\"><span class=\"verset v39\"><a href=\"https:\/\/lire.la-bible.net\/verset\/Marc\/5\/39\/NBS\"><span class=\"reference\">39<\/span><\/a>Il entre et leur dit : Pourquoi cette agitation et ces pleurs ? L&rsquo;enfant n&rsquo;est pas morte : elle dort.\u00a0<\/span><\/div>\n<div class=\"bloc_verset\"><span class=\"verset v40\"><a href=\"https:\/\/lire.la-bible.net\/verset\/Marc\/5\/40\/NBS\"><span class=\"reference\">40<\/span><\/a>Eux se moquaient de lui. Mais lui les chasse tous, prend avec lui le p\u00e8re et la m\u00e8re de l&rsquo;enfant, ainsi que ceux qui l&rsquo;accompagnaient, et il entre l\u00e0 o\u00f9 se trouvait l&rsquo;enfant.\u00a0<\/span><\/div>\n<div class=\"bloc_verset\"><span class=\"verset v41\"><a href=\"https:\/\/lire.la-bible.net\/verset\/Marc\/5\/41\/NBS\"><span class=\"reference\">41<\/span><\/a>Il saisit l&rsquo;enfant par la main et lui dit\u00a0:\u00a0<span class=\"i\">Talitha koum,\u00a0<\/span>ce qui se traduit : Jeune fille, je te le dis, r\u00e9veille-toi !\u00a0<\/span><\/div>\n<div class=\"bloc_verset\"><span class=\"verset v42\"><a href=\"https:\/\/lire.la-bible.net\/verset\/Marc\/5\/42\/NBS\"><span class=\"reference\">42<\/span><\/a>Aussit\u00f4t la jeune fille se leva et se mit \u00e0 marcher \u2014 en effet, elle avait douze ans. Ils furent saisis d&rsquo;une grande stup\u00e9faction.\u00a0<\/span><\/div>\n<div class=\"bloc_verset\"><span class=\"verset v43\"><a href=\"https:\/\/lire.la-bible.net\/verset\/Marc\/5\/43\/NBS\"><span class=\"reference\">43<\/span><\/a>Il leur fit de s\u00e9v\u00e8res recommandations pour que personne ne le sache, et il dit de lui donner \u00e0 manger.<\/span><\/div>\n<\/div>\n<div><\/div>\n<\/blockquote>\n<div>\n<ul>\n<li>Les deux r\u00e9cits sont ench\u00e2ss\u00e9s\u00a0:\u00a0Marc commence en nous racontant une histoire, puis en entame une autre, avant de terminer la premi\u00e8re\u00a0; on appelle cela une \u00ab\u00a0construction en sandwich\u00a0\u00bb. La partie <em>jambon<\/em> ou <em>fromage<\/em>, c\u2019est l\u2019exp\u00e9rience de cette femme\u00a0; le <em>pain<\/em>, celle de la fille de Ja\u00efros. Les deux r\u00e9cits s\u2019\u00e9clairent l\u2019un l\u2019autre.<\/li>\n<li><em>L\u2019intelligence du c\u0153ur<\/em>. La femme en \u00ab\u00a0vision interne\u00a0\u00bb, empathie du lecteur, touch\u00e9 par le r\u00e9cit des souffrances de cette femme. Donc \u00e9motion.<br \/>\nPuis les perceptions\u00a0:<br \/>\nattention \u00e0 la rumeur (elle avait appris ce qu\u2019on disait de J\u00e9sus)<br \/>\nintention, projet (si j\u2019arrive \u00e0 toucher ses v\u00eatements, je serai sauv\u00e9e)<br \/>\nr\u00e9action intime (elle ressentit en son corps qu\u2019elle \u00e9tait gu\u00e9rie)<br \/>\nconscience de la situation (sachant ce qui lui \u00e9tait arriv\u00e9)J\u00e9sus <em>partage<\/em> cette perception intuitive mais ne sait pas qui l\u2019a touch\u00e9, tout en cherchant \u00ab\u00a0celle\u00a0\u00bb qui a fait cela\u2026 Le partage des intuitions\/perceptions rapproche singuli\u00e8rement cette femme de J\u00e9sus (Marc l\u2019a r\u00e9dig\u00e9 ainsi pour que nous en ayons conscience).<\/li>\n<\/ul>\n<p>La r\u00e9action des disciples (\u00ab\u00a0Tu vois la foule qui te presse et tu demandes\u00a0: \u201cQui m\u2019a touch\u00e9\u00a0?\u201d\u00a0\u00bb) est totalement d\u00e9phas\u00e9e. Comme la foule, ils ne per\u00e7oivent que l\u2019arr\u00eat du cort\u00e8ge dans une situation d\u2019urgence.<\/p>\n<ul>\n<li><em>\u00ab\u00a0Fille\u00a0\u00bb <\/em>Marc \u00e9voque ainsi la fillette de Ja\u00efros dans la demande de son p\u00e8re\u00a0: <em>ma fillette<\/em>. Puis dans les termes des messagers\u00a0: <em>ta fille<\/em>. Ensuite, en arrivant chez Ja\u00efros, par trois fois, il est question du <em>petit enfant<\/em>. Enfin, dans la parole de gu\u00e9rison et dans la fin du r\u00e9cit, c\u2019est le mot <em>petite fille<\/em>, mais aussi <em>jeune fille<\/em> qui est utilis\u00e9.<\/li>\n<\/ul>\n<p>Concernant la femme \u00e0 la perte de sang, elle est d\u00e9sign\u00e9e dans le r\u00e9cit par l\u2019expression \u00ab\u00a0une certaine femme \u2013 une femme quelconque\u00a0\u00bb. Cependant, lorsque J\u00e9sus l\u2019a entendue dire \u00ab\u00a0toute la v\u00e9rit\u00e9\u00a0\u00bb, il s\u2019adresse \u00e0 elle en l\u2019appelant \u00ab\u00a0fille\u00a0\u00bb, avec sens de <em>filiation<\/em>.<\/p>\n<p>Pour la femme, il est question de douze ans de maladie. Quant \u00e0 la fillette, elle a douze ans. Ce parall\u00e9lisme permet de relier la femme et la fille de Ja\u00efros par ce laps de temps\u00a0: cette p\u00e9riode signe un moment dans lequel ni l\u2019une ni l\u2019autre n\u2019a \u00e9t\u00e9 pleinement f\u00e9minine. Dans les deux cas, nous rencontrons des cr\u00e9atures nouvelles qui <em>renaissent<\/em> gr\u00e2ce \u00e0 J\u00e9sus\u00a0; les verbes employ\u00e9s pour la fillette (se r\u00e9veiller, se relever) nous confortent dans cette interpr\u00e9tation.<\/p>\n<p>Il convient d\u2019aller plus loin. Comment s\u2019op\u00e8re cette renaissance, cette \u00ab\u00a0r\u00e9surrection\u00a0\u00bb\u00a0? Cela passe par le <em>niveau relationnel<\/em>. Pour la femme, isol\u00e9e et malade, le lien social est dissous\u00a0; elle doit se cacher. En lui adressant publiquement la parole, J\u00e9sus la restitue comme \u00ab\u00a0fille\u00a0\u00bb, autrement dit la fait entrer dans un <em>r\u00e9seau de filiation<\/em>\u00a0; elle est adopt\u00e9e, r\u00e9int\u00e9gr\u00e9e<\/p>\n<p>Tout autre est le cas de la \u00ab\u00a0fille de Ja\u00efros\u00a0\u00bb. Son anonymat cache une <em>appartenance<\/em>\u00a0: \u00ab\u00a0fille de\u00a0\u00bb. Il peut \u00eatre terriblement pesant d\u2019\u00eatre \u00ab\u00a0fille de\u00a0\u00bb, \u00ab\u00a0s\u0153ur de\u00a0\u00bb, \u00ab\u00a0femme de\u00a0\u00bb\u00a0! Que de souffrance\u00a0! Serait-ce l\u00e0 l\u2019origine de son anorexie (sugg\u00e9r\u00e9e par les psychanalystes qui se penchent sur ce texte)\u00a0? \u00c0 part le souci de lui assurer la nourriture indispensable, J\u00e9sus la d\u00e9livre de son appartenance en l\u2019appelant <em>jeune fille<\/em>. Elle devient une <em>personne \u00e0 part enti\u00e8re<\/em>.<\/p>\n<p>Elle est pass\u00e9e du stade de \u00ab\u00a0<em>ma<\/em> fille\u00a0\u00bb, c\u2019est-\u00e0-dire objet poss\u00e9d\u00e9 par son p\u00e8re \u00e0 une <em>existence propre de fille autonome<\/em>. \u00a0Une amie ex\u00e9g\u00e8te pr\u00e9cise\u00a0: \u00ab\u00a0C\u2019est le seul exemple dans lequel un p\u00e8re supplie J\u00e9sus pour une fille ; cela est important dans le contexte social de l\u2019\u00e9poque, quand on sait qu\u2019\u00e0 Rome, par exemple, on ne donnait pas de pr\u00e9nom aux filles mais on les nommait avec le nom gentilice au f\u00e9minin.\u00a0\u00bb<\/p>\n<p><strong>Conclusion<\/strong><\/p>\n<p>Tout ce jaillissement montre que l\u2019important (la femme dit \u00e0 J\u00e9sus toute la v\u00e9rit\u00e9 = <em>sa<\/em> v\u00e9rit\u00e9) se situe au niveau de <em>l\u2019existence personnelle<\/em>, de ce qui est v\u00e9cu dans la <em>souffrance<\/em>, avec <em>passion<\/em>\u2026 et <em>intelligence du c\u0153ur\u00a0<\/em>!<\/p>\n<p>Puissions-nous tous nous laisser inspirer par cette femme, devenue pour J\u00e9sus \u00ab\u00a0ma fille\u00a0\u00bb.<\/p>\n<p>Yvan Bourquin<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Deux r\u00e9cits, deux femmes. Dans l&rsquo;Evangile de Marc, elles sont au centre d&rsquo;un dispositif litt\u00e9raire appel\u00e9 \u00ab\u00a0sandwich\u00a0\u00bb.\u00a0 Cela nous apprend comment J\u00e9sus gu\u00e9rit. Marc 5 21J\u00e9sus regagna l&rsquo;autre rive en bateau, et une grande foule se rassembla aupr\u00e8s de lui. Il \u00e9tait au bord de la mer.\u00a0 22Un des chefs de la synagogue, nomm\u00e9 Ja\u00efros, &hellip; <a href=\"https:\/\/www.eren.ch\/barc\/2022\/05\/10\/sandwich-au-feminin\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;Sandwich au f\u00e9minin&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":20,"featured_media":3641,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2204],"tags":[2208],"class_list":["post-3636","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultes","tag-marc-5"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sandwich au f\u00e9minin &#8226; Paroisse r\u00e9form\u00e9e de La BARC<\/title>\n<meta name=\"description\" content=\"Deux r\u00e9cits, deux femmes. Dans l&#039;Evangile de Marc, elles sont au centre d&#039;un dispositif litt\u00e9raire appel\u00e9 &quot;sandwich&quot;.\u00a0 Cela nous apprend comment J\u00e9sus\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eren.ch\/barc\/2022\/05\/10\/sandwich-au-feminin\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sandwich au f\u00e9minin\" \/>\n<meta property=\"og:description\" content=\"Deux r\u00e9cits, deux femmes. Dans l&#039;Evangile de Marc, elles sont au centre d&#039;un dispositif litt\u00e9raire appel\u00e9 &quot;sandwich&quot;.\u00a0 Cela nous apprend comment J\u00e9sus\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eren.ch\/barc\/2022\/05\/10\/sandwich-au-feminin\/\" \/>\n<meta property=\"og:site_name\" content=\"Paroisse r\u00e9form\u00e9e de La BARC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eglise.EREN\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-10T04:17:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-11T13:06:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2022\/05\/Gospel_of_Luke_Chapter_8-31_Bible_Illustrations_by_Sweet_Media.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"831\" \/>\n\t<meta property=\"og:image:height\" content=\"610\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Nicole Rochat\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@egliseeren\" \/>\n<meta name=\"twitter:site\" content=\"@egliseeren\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicole Rochat\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2022\\\/05\\\/10\\\/sandwich-au-feminin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2022\\\/05\\\/10\\\/sandwich-au-feminin\\\/\"},\"author\":{\"name\":\"Nicole Rochat\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/#\\\/schema\\\/person\\\/00526893ede667c42160edcdd72c897d\"},\"headline\":\"Sandwich au f\u00e9minin\",\"datePublished\":\"2022-05-10T04:17:57+00:00\",\"dateModified\":\"2022-05-11T13:06:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2022\\\/05\\\/10\\\/sandwich-au-feminin\\\/\"},\"wordCount\":1287,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2022\\\/05\\\/10\\\/sandwich-au-feminin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/05\\\/Gospel_of_Luke_Chapter_8-31_Bible_Illustrations_by_Sweet_Media.jpeg\",\"keywords\":[\"Marc 5\"],\"articleSection\":[\"Cultes et pr\u00e9dications\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2022\\\/05\\\/10\\\/sandwich-au-feminin\\\/\",\"url\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2022\\\/05\\\/10\\\/sandwich-au-feminin\\\/\",\"name\":\"Sandwich au f\u00e9minin &#8226; Paroisse r\u00e9form\u00e9e de La BARC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2022\\\/05\\\/10\\\/sandwich-au-feminin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2022\\\/05\\\/10\\\/sandwich-au-feminin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/05\\\/Gospel_of_Luke_Chapter_8-31_Bible_Illustrations_by_Sweet_Media.jpeg\",\"datePublished\":\"2022-05-10T04:17:57+00:00\",\"dateModified\":\"2022-05-11T13:06:04+00:00\",\"description\":\"Deux r\u00e9cits, deux femmes. Dans l'Evangile de Marc, elles sont au centre d'un dispositif litt\u00e9raire appel\u00e9 \\\"sandwich\\\".\u00a0 Cela nous apprend comment J\u00e9sus\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2022\\\/05\\\/10\\\/sandwich-au-feminin\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2022\\\/05\\\/10\\\/sandwich-au-feminin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2022\\\/05\\\/10\\\/sandwich-au-feminin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/05\\\/Gospel_of_Luke_Chapter_8-31_Bible_Illustrations_by_Sweet_Media.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2022\\\/05\\\/Gospel_of_Luke_Chapter_8-31_Bible_Illustrations_by_Sweet_Media.jpeg\",\"width\":831,\"height\":610},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2022\\\/05\\\/10\\\/sandwich-au-feminin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sandwich au f\u00e9minin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/#website\",\"url\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/\",\"name\":\"Paroisse r\u00e9form\u00e9e de La BARC\",\"description\":\"B\u00f4le - Auvernier - Rochefort - Colombier\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/#organization\",\"name\":\"Paroisse de La BARC\",\"url\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/12\\\/logo-barc.png\",\"contentUrl\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/12\\\/logo-barc.png\",\"width\":240,\"height\":117,\"caption\":\"Paroisse de La BARC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eglise.EREN\",\"https:\\\/\\\/x.com\\\/egliseeren\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/\u00c9glise_r\u00e9form\u00e9e_\u00e9vang\u00e9lique_du_canton_de_Neuch\u00e2tel\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/#\\\/schema\\\/person\\\/00526893ede667c42160edcdd72c897d\",\"name\":\"Nicole Rochat\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3351e7924479d57b79df156d6aa8d62589afb331ba0f28f599ae364813966546?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3351e7924479d57b79df156d6aa8d62589afb331ba0f28f599ae364813966546?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3351e7924479d57b79df156d6aa8d62589afb331ba0f28f599ae364813966546?s=96&d=blank&r=g\",\"caption\":\"Nicole Rochat\"},\"url\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/author\\\/nrochat\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sandwich au f\u00e9minin &#8226; Paroisse r\u00e9form\u00e9e de La BARC","description":"Deux r\u00e9cits, deux femmes. Dans l'Evangile de Marc, elles sont au centre d'un dispositif litt\u00e9raire appel\u00e9 \"sandwich\".\u00a0 Cela nous apprend comment J\u00e9sus","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eren.ch\/barc\/2022\/05\/10\/sandwich-au-feminin\/","og_locale":"fr_FR","og_type":"article","og_title":"Sandwich au f\u00e9minin","og_description":"Deux r\u00e9cits, deux femmes. Dans l'Evangile de Marc, elles sont au centre d'un dispositif litt\u00e9raire appel\u00e9 \"sandwich\".\u00a0 Cela nous apprend comment J\u00e9sus","og_url":"https:\/\/www.eren.ch\/barc\/2022\/05\/10\/sandwich-au-feminin\/","og_site_name":"Paroisse r\u00e9form\u00e9e de La BARC","article_publisher":"https:\/\/www.facebook.com\/eglise.EREN","article_published_time":"2022-05-10T04:17:57+00:00","article_modified_time":"2022-05-11T13:06:04+00:00","og_image":[{"width":831,"height":610,"url":"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2022\/05\/Gospel_of_Luke_Chapter_8-31_Bible_Illustrations_by_Sweet_Media.jpeg","type":"image\/jpeg"}],"author":"Nicole Rochat","twitter_card":"summary_large_image","twitter_creator":"@egliseeren","twitter_site":"@egliseeren","twitter_misc":{"\u00c9crit par":"Nicole Rochat","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eren.ch\/barc\/2022\/05\/10\/sandwich-au-feminin\/#article","isPartOf":{"@id":"https:\/\/www.eren.ch\/barc\/2022\/05\/10\/sandwich-au-feminin\/"},"author":{"name":"Nicole Rochat","@id":"https:\/\/www.eren.ch\/barc\/#\/schema\/person\/00526893ede667c42160edcdd72c897d"},"headline":"Sandwich au f\u00e9minin","datePublished":"2022-05-10T04:17:57+00:00","dateModified":"2022-05-11T13:06:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eren.ch\/barc\/2022\/05\/10\/sandwich-au-feminin\/"},"wordCount":1287,"publisher":{"@id":"https:\/\/www.eren.ch\/barc\/#organization"},"image":{"@id":"https:\/\/www.eren.ch\/barc\/2022\/05\/10\/sandwich-au-feminin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2022\/05\/Gospel_of_Luke_Chapter_8-31_Bible_Illustrations_by_Sweet_Media.jpeg","keywords":["Marc 5"],"articleSection":["Cultes et pr\u00e9dications"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eren.ch\/barc\/2022\/05\/10\/sandwich-au-feminin\/","url":"https:\/\/www.eren.ch\/barc\/2022\/05\/10\/sandwich-au-feminin\/","name":"Sandwich au f\u00e9minin &#8226; Paroisse r\u00e9form\u00e9e de La BARC","isPartOf":{"@id":"https:\/\/www.eren.ch\/barc\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eren.ch\/barc\/2022\/05\/10\/sandwich-au-feminin\/#primaryimage"},"image":{"@id":"https:\/\/www.eren.ch\/barc\/2022\/05\/10\/sandwich-au-feminin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2022\/05\/Gospel_of_Luke_Chapter_8-31_Bible_Illustrations_by_Sweet_Media.jpeg","datePublished":"2022-05-10T04:17:57+00:00","dateModified":"2022-05-11T13:06:04+00:00","description":"Deux r\u00e9cits, deux femmes. Dans l'Evangile de Marc, elles sont au centre d'un dispositif litt\u00e9raire appel\u00e9 \"sandwich\".\u00a0 Cela nous apprend comment J\u00e9sus","breadcrumb":{"@id":"https:\/\/www.eren.ch\/barc\/2022\/05\/10\/sandwich-au-feminin\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eren.ch\/barc\/2022\/05\/10\/sandwich-au-feminin\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eren.ch\/barc\/2022\/05\/10\/sandwich-au-feminin\/#primaryimage","url":"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2022\/05\/Gospel_of_Luke_Chapter_8-31_Bible_Illustrations_by_Sweet_Media.jpeg","contentUrl":"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2022\/05\/Gospel_of_Luke_Chapter_8-31_Bible_Illustrations_by_Sweet_Media.jpeg","width":831,"height":610},{"@type":"BreadcrumbList","@id":"https:\/\/www.eren.ch\/barc\/2022\/05\/10\/sandwich-au-feminin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.eren.ch\/barc\/"},{"@type":"ListItem","position":2,"name":"Sandwich au f\u00e9minin"}]},{"@type":"WebSite","@id":"https:\/\/www.eren.ch\/barc\/#website","url":"https:\/\/www.eren.ch\/barc\/","name":"Paroisse r\u00e9form\u00e9e de La BARC","description":"B\u00f4le - Auvernier - Rochefort - Colombier","publisher":{"@id":"https:\/\/www.eren.ch\/barc\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eren.ch\/barc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.eren.ch\/barc\/#organization","name":"Paroisse de La BARC","url":"https:\/\/www.eren.ch\/barc\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eren.ch\/barc\/#\/schema\/logo\/image\/","url":"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2020\/12\/logo-barc.png","contentUrl":"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2020\/12\/logo-barc.png","width":240,"height":117,"caption":"Paroisse de La BARC"},"image":{"@id":"https:\/\/www.eren.ch\/barc\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eglise.EREN","https:\/\/x.com\/egliseeren","https:\/\/fr.wikipedia.org\/wiki\/\u00c9glise_r\u00e9form\u00e9e_\u00e9vang\u00e9lique_du_canton_de_Neuch\u00e2tel"]},{"@type":"Person","@id":"https:\/\/www.eren.ch\/barc\/#\/schema\/person\/00526893ede667c42160edcdd72c897d","name":"Nicole Rochat","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/3351e7924479d57b79df156d6aa8d62589afb331ba0f28f599ae364813966546?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3351e7924479d57b79df156d6aa8d62589afb331ba0f28f599ae364813966546?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3351e7924479d57b79df156d6aa8d62589afb331ba0f28f599ae364813966546?s=96&d=blank&r=g","caption":"Nicole Rochat"},"url":"https:\/\/www.eren.ch\/barc\/author\/nrochat\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/posts\/3636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/comments?post=3636"}],"version-history":[{"count":0,"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/posts\/3636\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/media\/3641"}],"wp:attachment":[{"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/media?parent=3636"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/categories?post=3636"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/tags?post=3636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}