{"id":4786,"date":"2024-08-20T14:07:48","date_gmt":"2024-08-20T12:07:48","guid":{"rendered":"https:\/\/www.eren.ch\/barc\/?p=4786"},"modified":"2025-04-08T15:42:10","modified_gmt":"2025-04-08T13:42:10","slug":"cetait-magique","status":"publish","type":"post","link":"https:\/\/www.eren.ch\/barc\/2024\/08\/20\/cetait-magique\/","title":{"rendered":"C&rsquo;\u00e9tait magique!"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">De retour d&rsquo;une semaine de camp dans le Jura, les jeunes du Passeport KT ont c\u00e9l\u00e9br\u00e9 le culte dimanche dernier. Voici quelques morceaux choisis.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-accueil\">Accueil<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Nous revenons d\u2019une semaine incroyable de camp dans le Jura, \u00e0 Vicques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous vivions dans un monde qui ressemblait \u00e0 l\u2019univers de Harry Potter, mais ce n\u2019\u00e9tait pas exactement Harry Potter. Nous n\u2019\u00e9tions pas \u00e0 Poudlard, mais \u00e0 CrossRoads, une autre \u00e9cole de sorci\u00e8res et sorciers. Une \u00e9cole \u00e9cossaise dirig\u00e9e par le Professeur McGill et qui poss\u00e8de une grande richesse : le Grand Grimoire de l\u2019Evangile. Un ouvrage extraordinaire qui a le pouvoir d\u2019ouvrir les esprits et d\u2019\u00e9clairer les relations humaines lorsqu\u2019on plonge \u00e0 l\u2019int\u00e9rieur. C&rsquo;est une \u00e9cole  sp\u00e9ciale qui change d\u2019endroit et qui a une mission \u00e0 accomplir : trouver les <em>Reliques de la vie<\/em>. <\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-priere\">Pri\u00e8re<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Tu nous aimes, Seigneur, tels que nous sommes, nous le savons bien.<br>Et pourtant, nous voulons si souvent te prouver que nous m\u00e9ritons ton amour.<br>Par nos paroles, par nos gestes, nous voulons te plaire.<br>Et nous oublions que toi, tu nous aimes en d\u00e9pit de tous nos efforts, tu nous aimes au-del\u00e0 de tous nos artifices.<br>Nous aimerions ne pas faire d\u2019erreur, ne pas d\u00e9cevoir, ne pas nous tromper.<br>Mais, m\u00eame si nous ne faisons pas tout juste, toi, tu ne cesses pas de nous aimer.<br>Et cela ravive notre confiance.<br>Amen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-message\">Message<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Durant le camp, le jeudi, un grand probl\u00e8me a frapp\u00e9 les magiciennes et magiciens&nbsp;: la Magie ne fonctionnait plus. Tr\u00e8s pratiquement, comme l\u2019entier de l\u2019\u00e9cole tournait gr\u00e2ce \u00e0 la magie, le premier probl\u00e8me a \u00e9t\u00e9 de nous \u00e9clairer&nbsp;! Nos lampes magiques refusaient de nous \u00e9clairer.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alors, par l\u2019intuition d\u2019un de nos professeurs. Nous sommes partis \u00e0 la recherche de tous ce que le grand grimoire de l\u2019\u00c9vangile disait \u00e0 propos de la lumi\u00e8re. Et nous sommes tomb\u00e9s sur ce texte biblique qui a illumin\u00e9 (c\u2019est le cas de le dire) toute notre journ\u00e9e&nbsp;:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Vous \u00eates la lumi\u00e8re du monde. Une ville situ\u00e9e sur une montagne ne peut \u00eatre cach\u00e9e; et on n&rsquo;allume pas une lampe pour la mettre sous le boisseau, mais on la met sur le chandelier, et elle \u00e9claire tous ceux qui sont dans la maison. Que votre lumi\u00e8re luise ainsi devant les hommes, afin qu&rsquo;ils voient vos bonnes \u0153uvres, et qu&rsquo;ils glorifient votre P\u00e8re qui est dans les cieux.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Matthieu 5,14-15<br><\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Nous avons donc commenc\u00e9 une qu\u00eate pour retrouver de la lumi\u00e8re, vu que nos baguettes \u00e9taient plus que d\u00e9fectueuses. Nous avons \u00e9t\u00e9 contraints de nous r\u00e9adapter \u00e0 cette tr\u00e8s ennuyeuse r\u00e9alit\u00e9. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019image ou la m\u00e9taphore de la lumi\u00e8re est pr\u00e9sente partout dans la Bible, dans l\u2019Ancien comme dans le Nouveau testament. Et nous avons scrut\u00e9 quelques morceaux choisis au travers des \u00c9vangiles et des proph\u00e8tes et des Psaumes. Pour d\u00e9couvrir une relique de la vie&nbsp;: la lampe du devenir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alors, c\u2019est quoi la lampe du devenir&nbsp;? Ce sont d\u2019abord des valeurs qui font vivre. Et particuli\u00e8rement la confiance, l\u2019esp\u00e9rance et l\u2019amour. Mais c\u2019est encore plus que cela&nbsp;! C\u2019est la flamme qui br\u00fble en nous et qui \u00e9claire les autres par notre \u00eatre, notre pr\u00e9sence, nos actes, nos paroles. Cette flamme est aussi celle de nos talents, des dons que nous avons re\u00e7us du Dieu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsqu\u2019on met ensemble les talents des uns et des autres et que nous nous regardons les uns les autres avec admiration\u2026 De la lumi\u00e8re jaillit&nbsp;! Il ne faut surtout pas \u00e9teindre cette lumi\u00e8re car c\u2019est une lumi\u00e8re saine et sainte. Une lumi\u00e8re qui \u00e9l\u00e8ve.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voici un petit passage d&rsquo;un discours \u00e9crit par Marianne Williamson et repris par Nelson Mandela lors de son entr\u00e9e \u00e0 la pr\u00e9sidence de l\u2019Afrique du Sud&nbsp;:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Nous sommes tous n\u00e9s pour briller, comme des enfants le font. Nous sommes n\u00e9s pour rendre manifeste la gloire de Dieu qui est en nous. Elle n&rsquo;est pas seulement chez certains d&rsquo;entre nous, elle est en chacun de nous.<br>Alors que nous laissons notre propre lumi\u00e8re briller, inconsciemment nous donnons aux autres la permission d&rsquo;en faire de m\u00eame. Alors que nous nous lib\u00e9rons de notre propre peur, notre pr\u00e9sence lib\u00e8re automatiquement les autres.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Ce texte exprime parfaitement bien le c\u0153ur de ce qu\u2019est la lampe du devenir. La lumi\u00e8re de la gloire de Dieu&nbsp;!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Chacun, chacune de nous est une parcelle de Dieu&nbsp;! Un \u00e9clat de Dieu, et contient une \u00e9tincelle de sa lumi\u00e8re. Ensemble, chacun, chacune, si nous nous r\u00e9unissons, si nous aimons, si nous dialoguons, si nous construisons le monde\u2026 Nos \u00e9tincelles se r\u00e9unissent et s\u2019embrase comme la lampe sur le chandelier dont parle l\u2019\u00c9vangile.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous avons parl\u00e9 de la gloire, car \u00eatre brillant c\u2019est un peu \u00eatre glorieux. Est-ce que la gloire, c\u2019est identique \u00e0 la c\u00e9l\u00e9brit\u00e9 ou \u00e0 la renomm\u00e9e&nbsp;; ce que beaucoup de personnes recherchent de nos jours\u2026 et peut-\u00eatre depuis toujours.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le monde d\u2019aujourd\u2019hui donne l\u2019illusion que la c\u00e9l\u00e9brit\u00e9 est \u00e0 port\u00e9e de tous\u2026 mais la gloire que le lumi\u00e8re de Dieu contient, est-ce cette c\u00e9l\u00e9brit\u00e9-l\u00e0&nbsp;?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Voici une jolie d\u00e9finition de la gloire, qui a \u00e9t\u00e9 inspir\u00e9e par le th\u00e9ologien Karl Barth&nbsp;:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">La gloire est l\u2019image la plus parfaite possible qu\u2019un \u00eatre (Dieu y compris) puisse donner au monde. Dieu aussi se montre dans sa gloire lorsqu\u2019il r\u00e9v\u00e8le au monde son image la plus parfaite possible. M\u00eame l\u2019enfant de la cr\u00e8che ou J\u00e9sus sur la croix sont des manifestations de la gloire de Dieu.<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019image la plus parfaite qu\u2019un \u00eatre puisse donner au monde&nbsp;? \u00c7a fait r\u00e9fl\u00e9chir\u2026 Ce serait tellement beau si le monde entier cherchait ce genre de gloire, c\u2019est-\u00e0-dire finalement \u00eatre totalement soi-m\u00eame, dans la perfection que Dieu a choisi pour lui. Car ils sont nombreux, les gens, les \u00e9v\u00e9nements aussi, qui vont essayer de faire en sorte que la lumi\u00e8re de notre gloire s\u2019\u00e9teigne petit \u00e0 petit.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alors, que peut-on faire pour rem\u00e9dier \u00e0 cela&nbsp;?<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Retrouver ce qui fait vraiment sens pour soi&nbsp;! Les relations saines, les amis, les parents, la famille\u2026 tous celles et ceux qui nous aime et qu\u2019on aime en retour. Faire de beaux projets \u2013 pas irr\u00e9alistes car on sera d\u00e9\u00e7u \u2013 mais r\u00e9alistes qui nous motivent et nous tirent en avant. Faire des choses agr\u00e9ables, respecter ceux qui vivent avec nous sur cette terre. \u00catre simples, humbles\u2026 mais lumineux&nbsp;!<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">Cette d\u00e9couverte nous invite \u00e0 une immense esp\u00e9rance&nbsp;! C\u2019est l\u2019esp\u00e9rance de tous les croyant-e-s. Dans la Bible, on l\u2019appelle le Royaume de Dieu\u2026 Nous l\u2019avons aussi abord\u00e9 dans notre camp.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour terminer, \u00e9coutons le magnifique texte qu\u2019\u00e0 \u00e9crit le proph\u00e8te \u00c9sa\u00efe pour parler de cette esp\u00e9rance.<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p class=\"wp-block-paragraph\">Le loup habitera avec l&rsquo;agneau, Et la panth\u00e8re se couchera avec le chevreau; Le veau, le lionceau, et le b\u00e9tail qu&rsquo;on engraisse, seront ensemble, Et un petit enfant les conduira.<br>La vache et l&rsquo;ourse auront un m\u00eame p\u00e2turage, Leurs petits un m\u00eame g\u00eete; Et le lion, comme le b\u0153uf, mangera de la paille.<br>Le nourrisson s&rsquo;\u00e9battra sur l&rsquo;antre de la vip\u00e8re, Et l&rsquo;enfant sevr\u00e9 mettra sa main dans la caverne du serpent.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00c9sa\u00efe 11,6-8<\/p>\n<\/blockquote>\n\n\n\n<p class=\"wp-block-paragraph\">En fait, cette esp\u00e9rance est celle d\u2019un monde o\u00f9 r\u00e8gne la paix. Les animaux de ce texte sont aussi des images pour parler des humains, comme dans une fable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">C\u2019est une utopie\u2026 mais qui ne r\u00eaverait pas d\u2019un monde o\u00f9 les forts prot\u00e8gent les faibles\u2026 ou mieux, o\u00f9 les forts enseignent aux faibles \u00e0 \u00eatre forts et o\u00f9 les soi-disant faibles enseignent aux forts l\u2019art de la douceur, de l\u2019humilit\u00e9, de la reconnaissance\u2026 qui sont en v\u00e9rit\u00e9 des forces.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Toute faiblesse peut devenir force et inversement.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quoi qu\u2019il en soit, la lampe du devenir est aussi un nid de la r\u00e9conciliation\u2026 elle \u00e9claire le chemin des humains vers le Royaume de Dieu.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Amen<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240818_083625-1024x575.jpg\" alt=\"\" class=\"wp-image-4796\" srcset=\"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240818_083625-1024x575.jpg 1024w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240818_083625-300x169.jpg 300w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240818_083625-768x432.jpg 768w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240818_083625-1536x863.jpg 1536w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240818_083625-2048x1151.jpg 2048w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240818_083625-1200x674.jpg 1200w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-temoignages-des-moments-forts-du-camp\">T\u00e9moignages des moments forts du camp<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">De retour d\u2019une semaine riche en exp\u00e9riences, les souvenirs foisonnent. On aimerait \u00e0 la fois tout raconter et en m\u00eame temps on n\u2019arrive pas parfaitement \u00e0 mettre des mots sur tout ce que l\u2019on a v\u00e9cu. Mais par petites touches, comme des flashs, nous souhaitons partager ce matin un peu de ce qu\u2019a \u00e9t\u00e9 la vie \u00e0 CrossRoads.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-les-4-maisons\">Les 4 maisons<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le lundi, nous avons \u00e9t\u00e9 r\u00e9partis en diff\u00e9rentes maisons.&nbsp;Ce qui est rigolo, c\u2019est que j\u2019ai d\u00e9couvert le dernier jour qu\u2019elles repr\u00e9sentaient chacune un des \u00e9vang\u00e9listes: Matthieu, Marc, Luc et Jean.&nbsp;Chaque maison a d\u00fb trouver sa devise et confectionner son blason.<\/p>\n\n\n\n<h6 class=\"wp-block-heading\" id=\"h-feudelion\">Feudelion<\/h6>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" width=\"965\" height=\"1024\" src=\"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240820_133023-965x1024.jpg\" alt=\"\" class=\"wp-image-4790\" style=\"width:360px\" srcset=\"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240820_133023-965x1024.jpg 965w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240820_133023-283x300.jpg 283w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240820_133023-768x815.jpg 768w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240820_133023-1448x1536.jpg 1448w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240820_133023-1930x2048.jpg 1930w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240820_133023-1200x1273.jpg 1200w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><figcaption class=\"wp-element-caption\">FEUDELION &#8211; Marc<br>\u00ab\u00a0Je prot\u00e8ge les autres gr\u00e2ce \u00e0 ma flamme\u00a0\u00bb<\/figcaption><\/figure>\n<\/div>\n\n\n<h6 class=\"wp-block-heading\" id=\"h-taureaudairain\">Taureaudairain<\/h6>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" width=\"874\" height=\"1024\" src=\"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/original_662f2a64-13c8-40c4-b805-19e56b5d4e39_IMG_20240820_133048-874x1024.jpg\" alt=\"\" class=\"wp-image-4791\" style=\"width:360px\" srcset=\"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/original_662f2a64-13c8-40c4-b805-19e56b5d4e39_IMG_20240820_133048-874x1024.jpg 874w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/original_662f2a64-13c8-40c4-b805-19e56b5d4e39_IMG_20240820_133048-256x300.jpg 256w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/original_662f2a64-13c8-40c4-b805-19e56b5d4e39_IMG_20240820_133048-768x900.jpg 768w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/original_662f2a64-13c8-40c4-b805-19e56b5d4e39_IMG_20240820_133048-1311x1536.jpg 1311w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/original_662f2a64-13c8-40c4-b805-19e56b5d4e39_IMG_20240820_133048-1748x2048.jpg 1748w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/original_662f2a64-13c8-40c4-b805-19e56b5d4e39_IMG_20240820_133048-1200x1406.jpg 1200w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><figcaption class=\"wp-element-caption\">TAUREAUDAIRAIN &#8211; Luc<br>\u00ab\u00a0L\u00e0 o\u00f9 est votre tr\u00e9sor, l\u00e0 aussi est votre c\u0153ur\u00a0\u00bb<\/figcaption><\/figure>\n<\/div>\n\n\n<h6 class=\"wp-block-heading\" id=\"h-messange\">Messange<\/h6>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" width=\"940\" height=\"1024\" src=\"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240820_132920-940x1024.jpg\" alt=\"\" class=\"wp-image-4789\" style=\"width:360px\" srcset=\"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240820_132920-940x1024.jpg 940w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240820_132920-275x300.jpg 275w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240820_132920-768x836.jpg 768w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240820_132920-1410x1536.jpg 1410w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240820_132920-1881x2048.jpg 1881w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240820_132920-1200x1307.jpg 1200w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><figcaption class=\"wp-element-caption\">MESSANGE &#8211; Matthieu<br>\u00ab\u00a0Sur chaque pierre noire pousse une feuille d&rsquo;or\u00a0\u00bb<\/figcaption><\/figure>\n<\/div>\n\n\n<h6 class=\"wp-block-heading\" id=\"h-aiglefin\">Aiglefin<\/h6>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" width=\"978\" height=\"1024\" src=\"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240820_133007-978x1024.jpg\" alt=\"\" class=\"wp-image-4787\" style=\"width:360px\" srcset=\"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240820_133007-978x1024.jpg 978w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240820_133007-287x300.jpg 287w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240820_133007-768x804.jpg 768w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240820_133007-1467x1536.jpg 1467w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240820_133007-1956x2048.jpg 1956w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240820_133007-1200x1256.jpg 1200w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><figcaption class=\"wp-element-caption\">AIGLEFIN &#8211; Jean<br>\u00ab\u00a0La justice est la cl\u00e9 du c\u0153ur et de la raison\u00a0\u00bb<\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Le soir, nous avons particip\u00e9 \u00e0 des cours sp\u00e9ciaux :&nbsp;un atelier de botanique, un cours de divination par les cartes,&nbsp;un questionnaire Harry Potter. Nous avons aussi appris une langue, le <em>Fourchelangue<\/em>, et ce qui m\u2019a beaucoup plu c\u2019\u00e9tait de devoir dresser un Flemargneux en lui donnant \u00e0 manger et en lui apprenant des tours. C\u2019\u00e9tait une super premi\u00e8re journ\u00e9e qui ouvrait magnifiquement ce camp.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-le-grand-concours-des-highlands\">Le grand concours des Highlands<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Un camp de KT est un savant m\u00e9lange entre des moments de d\u00e9couverte de r\u00e9cits de la Bible, de discussions parfois intenses, souvent profondes, et des temps de d\u00e9tente qui favorisent le vivre-ensemble.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le mardi soir, nous avons eu la chance de participer au grand concours des Highlands. Un jeu \u00e9cossais sorcier.&nbsp;Pour commencer le professeur Mac Pherlain nous a appris une danse de la victoire. C\u2019est une gigue \u00e9cossaise extr\u00eamement compliqu\u00e9e.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il y avait 5 postes. Le premier \u00e9tait le lancer de b\u00fbches. Il consistait \u00e0 lancer des b\u00fbches dans la largeur d\u2019un terrain de p\u00e9tanque le plus loin possible sans toucher le bord.&nbsp;On pouvait aussi shooter les b\u00fbches adversaires et il y avait un avantage \u00e0 avoir de grosses b\u00fbches. Il y avait d\u2019autres sports comme la lutte, le tir \u00e0 la corde et la course aux sacs. Mais je vais plut\u00f4t vous parler du footby-balai, un sport typique du monde des sorciers. Il ressemble au football des moldus mais sur un balai. On portait aussi une sorte de corde accroch\u00e9e au dos et on devait arracher celle des adversaires. L\u2019\u00e9quipe qui en avait rapport\u00e9 le plus gagnait un point. Le concours s\u2019est poursuivi jusqu\u2019\u00e0 la nuit tomb\u00e9e. C\u2019\u00e9tait sportif et joyeux malgr\u00e9 les quelques bless\u00e9s.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-la-marche-dans-la-foret-formidable\"><strong>La marche dans la For\u00eat Formidable<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Le mercredi apr\u00e8s-midi, nous sommes partis \u00e0 la recherche d\u2019ingr\u00e9dients dans la For\u00eat formidable et, par la m\u00eame occasion, nous sommes all\u00e9s chez un mage qui redonne vie aux animaux. Arriv\u00e9s au bout du chemin, nous devions prendre un bus magique mais nous l\u2019avons rat\u00e9.&nbsp; Heureusement, Yves, le professeur de la maison Aiglefin et conducteur a fait des allers-retours jusqu\u2019\u00e0 la maison du mage.&nbsp; Pour savoir qui allait dans la voiture, nous avons fait un jeu qui s\u2019appelle \u201cIchapo\u201d, les 6 premiers perdants partaient dans la voiture.&nbsp; Cette apr\u00e8s-midi \u00e9tait vraiment super malgr\u00e9 nos malheurs quand nous avons rat\u00e9 le bus.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-le-mage-qui-redonne-vie-aux-animaux\"><strong>Le mage qui redonne vie aux animaux<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s un chemin pour y aller un peu compliqu\u00e9, nous sommes finalement arriv\u00e9s chez le mage qui redonne vie aux animaux. Il s&rsquo;agit en fait du mus\u00e9e de taxidermie de Vicques.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous avons pu regarder un petit film explicatif sur le processus pour empailler une vache et ce qu\u2019est la taxidermie en g\u00e9n\u00e9ral.&nbsp;Nous avons fait la visite du mus\u00e9e et nous avons d\u00fb choisir un animal et, gr\u00e2ce \u00e0 nos baguettes magiques et notre imagination, lui redonner vie.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pour le retour, c&rsquo;est notre fid\u00e8le conducteur D\u00e9d\u00e9 qui nous a conduit. Mais le car \u00e9tait bloqu\u00e9 par des branchages. Alors D\u00e9d\u00e9 a pris sa cisaille et a coup\u00e9 des branches pour qu&rsquo;on puisse passer. C\u2019est ainsi que nous sommes rentr\u00e9s pour rechercher de nouvelles reliques de la vie.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-le-grand-festin\"><strong>Le grand festin<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Dans le monde fantastique de CrossRoads, le temps n\u2019est pas le m\u00eame que dans le monde des moldus. Un ph\u00e9nom\u00e8ne \u00e9trange fait qu\u2019on a l\u2019impression que l\u2019on vient d\u2019arriver et \u2026 pouf!&#8230; c\u2019est d\u00e9j\u00e0 jeudi ! Eh oui, m\u00eame au KT, toutes les bonnes choses ont une fin. Mais il faut que la fin soit belle.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Jeudi soir, avant le grand festin, une \u00e9quipe de d\u00e9corateurs s\u2019est affair\u00e9e afin de v\u00eatir les tables de nappes blanches, de p\u00e9tales de roses d\u2019or, de diamants et d\u2019autres pierres pr\u00e9cieuses ainsi que de chandelles. Il y avait aussi des livres, des crapauds, de magnifiques serviettes et m\u00eame des serpents\u2026 Mais rassurez-vous, leur c\u0153ur ne battait plus!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Apr\u00e8s, a eu lieu le banquet de cr\u00eapes pr\u00e9par\u00e9es par nos f\u00e9es de la cuisine! C\u2019\u00e9tait vraiment d\u00e9licieux et nous avons pass\u00e9 de bons moments autour d\u2019un bon repas dans la joie et la bonne humeur. Apr\u00e8s ce d\u00e9licieux festin, un groupe s\u2019est propos\u00e9 pour cr\u00e9er des animations telles que des sketchs comiques sur Harry Potter qui ont fait rigoler tout le public et un blind-test avec une petite course.&nbsp; Mais aussi un spectacle d\u2019impro fait et pr\u00e9sent\u00e9 par tous. Cette soir\u00e9e \u00e9tait dr\u00f4le et amusante. Puis en fin de soir\u00e9e nous avons fait une boum dans les salles communes. Lors de cette soir\u00e9e nous avons tous pass\u00e9 un bon moment et nous sommes reconnaissants envers les monos d\u2019avoir tout organis\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-les-lanternes\"><strong>Les lanternes<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">A la fin du camp, tout le monde est un peu transform\u00e9. On ne repart pas tout \u00e0 fait comme on est arriv\u00e9s. On n\u2019a plus besoin de la magie de nos baguettes lorsqu\u2019une autre forme de magie a op\u00e9r\u00e9.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le jeudi apr\u00e8s-midi, comme la magie ne fonctionnait pas, on ne pouvait pas faire des feux d\u2019artifice.&nbsp; A la place, nous avons d\u00e9cor\u00e9 des lanternes chinoises. Dessus, nous pouvions \u00e9crire ou dessiner des v\u0153ux ou des choses importantes pour nous.&nbsp;Il nous fallait faire attention de ne pas les percer en les d\u00e9corant, car elles \u00e9taient en papier.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Vers minuit nous avons eu un rassemblement afin de voir nos lanternes s\u2019envoler.&nbsp;C\u2019\u00e9tait \u00e9mouvant et magique \u00e0 la fois de voir ces lumi\u00e8res flotter dans les airs.&nbsp;Nos v\u0153ux semblaient s\u2019envoler vers le ciel alors que nous \u00e9tions toutes et tous r\u00e9unis pour notre derni\u00e8re soir\u00e9e ensemble.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Notre lanterne \u00e9tait munie d\u2019une ficelle afin qu\u2019elle ne pollue et n&rsquo;ab\u00eeme pas les champs aux alentours. C\u2019\u00e9tait vraiment un magnifique moment.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-priere-d-intercession\">Pri\u00e8re d&rsquo;intercession<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Seigneur, nous te prions pour tous ceux qui sont dans le besoin.<br>Soutiens-les peu importe qui ils sont, que leur peine soit physique ou morale.<br>S\u2019il-te-pla\u00eet, aide-les.&nbsp;<br>Nous te prions<br>Pour que les personnes en d\u00e9pression retrouvent la joie de vivre.<br>Pour que les malades gu\u00e9rissent et retrouvent la forme.<br>Pour soulager la solitude de certains.<br>Pour apaiser tous nos maux quels qu\u2019ils soient.<br>Pour que tous nos probl\u00e8mes, qui semblent insurmontables, se r\u00e9solvent.<br>Pour que les migrants, quelles que soient leurs raisons de quitter leur maison,<br>trouvent enfin un chez soi.<br>Fais en sorte que chacun et chacune d\u2019entre nous ait le sourire aux l\u00e8vres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Notre P\u00e8re, nous te prions aujourd\u2019hui pour que les guerres s\u2019arr\u00eatent.<br>Prot\u00e8ge les familles dans le besoin comme tu le fais pour nous.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Notre Dieu, aide-nous \u00e0 faire en sorte que les d\u00e9chets dans les mers, la pollution lumineuse, la famine et la m\u00e9t\u00e9o ind\u00e9cise s\u2019arr\u00eatent. Que la glace ne fonde plus, que les animaux en voie de disparition se repeuplent, que la verdure repousse l\u00e0 o\u00f9 il n\u2019y en a plus et que tout \u00e7a ne soit plus qu\u2019un mauvais souvenir.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nous te remercions aussi pour la joie et l\u2019amiti\u00e9 que nous partageons. Nous te prions pour tous ceux qui vivent de tels moments.&nbsp;<br>Nous pensons particuli\u00e8rement aux \u00e9l\u00e8ves et aux professeurs dont la rentr\u00e9e est imminente. Amen<\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-priere-de-reconnaissanc-e\"><strong>Pri\u00e8re de reconnaissanc<\/strong>e<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Seigneur, nous te remercions pour ce magnifique camp o\u00f9 nous avons eu des discussions profondes et enrichissantes dans un cadre de bienveillance qui nous permet d\u2019\u00eatre soi-m\u00eame.<br>Merci de nous avoir accompagn\u00e9s et soutenus durant ce camp comme tous les jours.<br>On te remercie de nous donner la chance de pouvoir nous nourrir en suffisance.&nbsp;<br>Nous avons appr\u00e9ci\u00e9 d&rsquo;\u00eatre dans un cadre idyllique sous une m\u00e9t\u00e9o formidable qui nous a permis de partager de bons moments.<br>Nous avons rencontr\u00e9 de nouvelles personnes avec lesquelles nous avons cr\u00e9\u00e9 des liens de confiance.<br>Nous avons pu laisser vivre pleinement nos \u00e9motions.<br>Chacun a pu \u00eatre authentique dans un cadre sain.<br>Nous te remercions pour tout cela.<br>Nous retenons tous ces souvenirs cr\u00e9\u00e9s ensemble, accompagn\u00e9s de fous rires et de bonheur.<br>Amen<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"575\" src=\"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240815_185015-1024x575.jpg\" alt=\"\" class=\"wp-image-4792\" srcset=\"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240815_185015-1024x575.jpg 1024w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240815_185015-300x169.jpg 300w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240815_185015-768x432.jpg 768w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240815_185015-1536x863.jpg 1536w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240815_185015-2048x1151.jpg 2048w, https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/IMG_20240815_185015-1200x674.jpg 1200w\" sizes=\"(max-width: 709px) 85vw, (max-width: 909px) 67vw, (max-width: 1362px) 62vw, 840px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-la-gazette\">La Gazette<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Voici notre journal de camp \u00e0 lire ici ou \u00e0 t\u00e9l\u00e9charger.<\/p>\n\n\n\n<div data-wp-interactive=\"core\/file\" class=\"wp-block-file\"><object data-wp-bind--hidden=\"!state.hasPdfPreview\" hidden class=\"wp-block-file__embed\" data=\"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/Gazette-JouralCamp-2024.pdf\" type=\"application\/pdf\" style=\"width:100%;height:600px\" aria-label=\"Contenu embarqu\u00e9 Gazette-JouralCamp-2024.\"><\/object><a id=\"wp-block-file--media-9ef579e4-f084-4f90-90b1-a2a34168a769\" href=\"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/Gazette-JouralCamp-2024.pdf\">Gazette-JouralCamp-2024<\/a><a href=\"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/Gazette-JouralCamp-2024.pdf\" class=\"wp-block-file__button wp-element-button\" download aria-describedby=\"wp-block-file--media-9ef579e4-f084-4f90-90b1-a2a34168a769\">T\u00e9l\u00e9charger<\/a><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"h-bravo-a-toute-l-equipe\">Bravo \u00e0 toute l&rsquo;\u00e9quipe!<\/h2>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-les-joyeux-eleves-de-l-ecole-de-crossroads-les-catechumenes\">Les joyeux \u00e9l\u00e8ves de l&rsquo;\u00e9cole de CrossRoads (les cat\u00e9chum\u00e8nes)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Am\u00e9lie, Camille, Cl\u00e9mence, Elo\u00efse, Ga\u00ebtan, Ga\u00ebtan, Julie, Lea, Line, Lise, Lou-Ann, Ludovico, Lydia, Ma\u00eblane, Margaux, Samuel, Sofia, Soline, Victoria, Zo\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-le-staff-de-l-ecole-les-moniteurs-trices\">Le staff de l&rsquo;\u00e9cole (les moniteurs-trices)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Aliz\u00e9e, Ambre, Elise, Emilie, Eva Rosa, Eve, Chlo\u00e9, Hermine, Jonathan, Lucien, Matthias, Zo\u00e9, Zo\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-les-profs-l-equipe-de-direction\">Les profs (l&rsquo;\u00e9quipe de direction)<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Antoine, Diane, Jean-Marc, Sarah, Yves<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-les-fees-de-la-cuisine\">Les f\u00e9es de la cuisine<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Antoinette, Erika, Yvette<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De retour d&rsquo;une semaine de camp dans le Jura, les jeunes du Passeport KT ont c\u00e9l\u00e9br\u00e9 le culte dimanche dernier. Voici quelques morceaux choisis. Accueil Nous revenons d\u2019une semaine incroyable de camp dans le Jura, \u00e0 Vicques. Nous vivions dans un monde qui ressemblait \u00e0 l\u2019univers de Harry Potter, mais ce n\u2019\u00e9tait pas exactement Harry &hellip; <a href=\"https:\/\/www.eren.ch\/barc\/2024\/08\/20\/cetait-magique\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;C&rsquo;\u00e9tait magique!&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":15,"featured_media":4794,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2204],"tags":[],"class_list":["post-4786","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultes"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>C&#039;\u00e9tait magique! &#8226; Paroisse r\u00e9form\u00e9e de La BARC<\/title>\n<meta name=\"description\" content=\"De retour d&#039;une semaine de camp dans le Jura, les jeunes du Passeport KT ont c\u00e9l\u00e9br\u00e9 le culte dimanche dernier. Morceaux choisis.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eren.ch\/barc\/2024\/08\/20\/cetait-magique\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"C&#039;\u00e9tait magique!\" \/>\n<meta property=\"og:description\" content=\"De retour d&#039;une semaine de camp dans le Jura, les jeunes du Passeport KT ont c\u00e9l\u00e9br\u00e9 le culte dimanche dernier. Morceaux choisis.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eren.ch\/barc\/2024\/08\/20\/cetait-magique\/\" \/>\n<meta property=\"og:site_name\" content=\"Paroisse r\u00e9form\u00e9e de La BARC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eglise.EREN\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/diane.friedli\" \/>\n<meta property=\"article:published_time\" content=\"2024-08-20T12:07:48+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-08T13:42:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/DSC04066-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Diane Friedli\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@egliseeren\" \/>\n<meta name=\"twitter:site\" content=\"@egliseeren\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Diane Friedli\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2024\\\/08\\\/20\\\/cetait-magique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2024\\\/08\\\/20\\\/cetait-magique\\\/\"},\"author\":{\"name\":\"Diane Friedli\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/#\\\/schema\\\/person\\\/0956e55ec238a99f35c4cd7e85381762\"},\"headline\":\"C&rsquo;\u00e9tait magique!\",\"datePublished\":\"2024-08-20T12:07:48+00:00\",\"dateModified\":\"2025-04-08T13:42:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2024\\\/08\\\/20\\\/cetait-magique\\\/\"},\"wordCount\":3165,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2024\\\/08\\\/20\\\/cetait-magique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/08\\\/DSC04066-scaled.jpg\",\"articleSection\":[\"Cultes et pr\u00e9dications\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2024\\\/08\\\/20\\\/cetait-magique\\\/\",\"url\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2024\\\/08\\\/20\\\/cetait-magique\\\/\",\"name\":\"C'\u00e9tait magique! &#8226; Paroisse r\u00e9form\u00e9e de La BARC\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2024\\\/08\\\/20\\\/cetait-magique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2024\\\/08\\\/20\\\/cetait-magique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/08\\\/DSC04066-scaled.jpg\",\"datePublished\":\"2024-08-20T12:07:48+00:00\",\"dateModified\":\"2025-04-08T13:42:10+00:00\",\"description\":\"De retour d'une semaine de camp dans le Jura, les jeunes du Passeport KT ont c\u00e9l\u00e9br\u00e9 le culte dimanche dernier. Morceaux choisis.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2024\\\/08\\\/20\\\/cetait-magique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2024\\\/08\\\/20\\\/cetait-magique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2024\\\/08\\\/20\\\/cetait-magique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/08\\\/DSC04066-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2024\\\/08\\\/DSC04066-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/2024\\\/08\\\/20\\\/cetait-magique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"C&rsquo;\u00e9tait magique!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/#website\",\"url\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/\",\"name\":\"Paroisse r\u00e9form\u00e9e de La BARC\",\"description\":\"B\u00f4le - Auvernier - Rochefort - Colombier\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/#organization\",\"name\":\"Paroisse de La BARC\",\"url\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/12\\\/logo-barc.png\",\"contentUrl\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/wp-content\\\/uploads\\\/sites\\\/4\\\/2020\\\/12\\\/logo-barc.png\",\"width\":240,\"height\":117,\"caption\":\"Paroisse de La BARC\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eglise.EREN\",\"https:\\\/\\\/x.com\\\/egliseeren\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/\u00c9glise_r\u00e9form\u00e9e_\u00e9vang\u00e9lique_du_canton_de_Neuch\u00e2tel\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/#\\\/schema\\\/person\\\/0956e55ec238a99f35c4cd7e85381762\",\"name\":\"Diane Friedli\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4174ee343655321c9dbd4d2c6ee9c77ede314be9a69b089058a09978eeae611?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4174ee343655321c9dbd4d2c6ee9c77ede314be9a69b089058a09978eeae611?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/f4174ee343655321c9dbd4d2c6ee9c77ede314be9a69b089058a09978eeae611?s=96&d=blank&r=g\",\"caption\":\"Diane Friedli\"},\"sameAs\":[\"https:\\\/\\\/dianefriedli.ch\\\/\",\"https:\\\/\\\/www.facebook.com\\\/diane.friedli\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCNrNBZYbsUHnqKGrrw3JSfw\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/\u00c9glise_r\u00e9form\u00e9e_\u00e9vanglique_du_canton_de_Neuch\u00e2tel\"],\"honorificPrefix\":\"Mme\",\"birthDate\":\"1980-10-28\",\"gender\":\"femme\",\"knowsAbout\":[\"th\u00e9ologie\",\"cat\u00e9ch\u00e8se\",\"vulgarisation th\u00e9ologique\",\"pr\u00e9dication\"],\"knowsLanguage\":[\"fran\u00e7ais\",\"allemand\",\"anglais\"],\"jobTitle\":\"pasteure\",\"worksFor\":\"EREN\",\"url\":\"https:\\\/\\\/www.eren.ch\\\/barc\\\/author\\\/dfriedli\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"C'\u00e9tait magique! &#8226; Paroisse r\u00e9form\u00e9e de La BARC","description":"De retour d'une semaine de camp dans le Jura, les jeunes du Passeport KT ont c\u00e9l\u00e9br\u00e9 le culte dimanche dernier. Morceaux choisis.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eren.ch\/barc\/2024\/08\/20\/cetait-magique\/","og_locale":"fr_FR","og_type":"article","og_title":"C'\u00e9tait magique!","og_description":"De retour d'une semaine de camp dans le Jura, les jeunes du Passeport KT ont c\u00e9l\u00e9br\u00e9 le culte dimanche dernier. Morceaux choisis.","og_url":"https:\/\/www.eren.ch\/barc\/2024\/08\/20\/cetait-magique\/","og_site_name":"Paroisse r\u00e9form\u00e9e de La BARC","article_publisher":"https:\/\/www.facebook.com\/eglise.EREN","article_author":"https:\/\/www.facebook.com\/diane.friedli","article_published_time":"2024-08-20T12:07:48+00:00","article_modified_time":"2025-04-08T13:42:10+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/DSC04066-scaled.jpg","type":"image\/jpeg"}],"author":"Diane Friedli","twitter_card":"summary_large_image","twitter_creator":"@egliseeren","twitter_site":"@egliseeren","twitter_misc":{"\u00c9crit par":"Diane Friedli","Dur\u00e9e de lecture estim\u00e9e":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eren.ch\/barc\/2024\/08\/20\/cetait-magique\/#article","isPartOf":{"@id":"https:\/\/www.eren.ch\/barc\/2024\/08\/20\/cetait-magique\/"},"author":{"name":"Diane Friedli","@id":"https:\/\/www.eren.ch\/barc\/#\/schema\/person\/0956e55ec238a99f35c4cd7e85381762"},"headline":"C&rsquo;\u00e9tait magique!","datePublished":"2024-08-20T12:07:48+00:00","dateModified":"2025-04-08T13:42:10+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eren.ch\/barc\/2024\/08\/20\/cetait-magique\/"},"wordCount":3165,"publisher":{"@id":"https:\/\/www.eren.ch\/barc\/#organization"},"image":{"@id":"https:\/\/www.eren.ch\/barc\/2024\/08\/20\/cetait-magique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/DSC04066-scaled.jpg","articleSection":["Cultes et pr\u00e9dications"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eren.ch\/barc\/2024\/08\/20\/cetait-magique\/","url":"https:\/\/www.eren.ch\/barc\/2024\/08\/20\/cetait-magique\/","name":"C'\u00e9tait magique! &#8226; Paroisse r\u00e9form\u00e9e de La BARC","isPartOf":{"@id":"https:\/\/www.eren.ch\/barc\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eren.ch\/barc\/2024\/08\/20\/cetait-magique\/#primaryimage"},"image":{"@id":"https:\/\/www.eren.ch\/barc\/2024\/08\/20\/cetait-magique\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/DSC04066-scaled.jpg","datePublished":"2024-08-20T12:07:48+00:00","dateModified":"2025-04-08T13:42:10+00:00","description":"De retour d'une semaine de camp dans le Jura, les jeunes du Passeport KT ont c\u00e9l\u00e9br\u00e9 le culte dimanche dernier. Morceaux choisis.","breadcrumb":{"@id":"https:\/\/www.eren.ch\/barc\/2024\/08\/20\/cetait-magique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eren.ch\/barc\/2024\/08\/20\/cetait-magique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eren.ch\/barc\/2024\/08\/20\/cetait-magique\/#primaryimage","url":"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/DSC04066-scaled.jpg","contentUrl":"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2024\/08\/DSC04066-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/www.eren.ch\/barc\/2024\/08\/20\/cetait-magique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.eren.ch\/barc\/"},{"@type":"ListItem","position":2,"name":"C&rsquo;\u00e9tait magique!"}]},{"@type":"WebSite","@id":"https:\/\/www.eren.ch\/barc\/#website","url":"https:\/\/www.eren.ch\/barc\/","name":"Paroisse r\u00e9form\u00e9e de La BARC","description":"B\u00f4le - Auvernier - Rochefort - Colombier","publisher":{"@id":"https:\/\/www.eren.ch\/barc\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eren.ch\/barc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.eren.ch\/barc\/#organization","name":"Paroisse de La BARC","url":"https:\/\/www.eren.ch\/barc\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eren.ch\/barc\/#\/schema\/logo\/image\/","url":"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2020\/12\/logo-barc.png","contentUrl":"https:\/\/www.eren.ch\/barc\/wp-content\/uploads\/sites\/4\/2020\/12\/logo-barc.png","width":240,"height":117,"caption":"Paroisse de La BARC"},"image":{"@id":"https:\/\/www.eren.ch\/barc\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eglise.EREN","https:\/\/x.com\/egliseeren","https:\/\/fr.wikipedia.org\/wiki\/\u00c9glise_r\u00e9form\u00e9e_\u00e9vang\u00e9lique_du_canton_de_Neuch\u00e2tel"]},{"@type":"Person","@id":"https:\/\/www.eren.ch\/barc\/#\/schema\/person\/0956e55ec238a99f35c4cd7e85381762","name":"Diane Friedli","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/f4174ee343655321c9dbd4d2c6ee9c77ede314be9a69b089058a09978eeae611?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f4174ee343655321c9dbd4d2c6ee9c77ede314be9a69b089058a09978eeae611?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f4174ee343655321c9dbd4d2c6ee9c77ede314be9a69b089058a09978eeae611?s=96&d=blank&r=g","caption":"Diane Friedli"},"sameAs":["https:\/\/dianefriedli.ch\/","https:\/\/www.facebook.com\/diane.friedli","https:\/\/www.youtube.com\/channel\/UCNrNBZYbsUHnqKGrrw3JSfw","https:\/\/fr.wikipedia.org\/wiki\/\u00c9glise_r\u00e9form\u00e9e_\u00e9vanglique_du_canton_de_Neuch\u00e2tel"],"honorificPrefix":"Mme","birthDate":"1980-10-28","gender":"femme","knowsAbout":["th\u00e9ologie","cat\u00e9ch\u00e8se","vulgarisation th\u00e9ologique","pr\u00e9dication"],"knowsLanguage":["fran\u00e7ais","allemand","anglais"],"jobTitle":"pasteure","worksFor":"EREN","url":"https:\/\/www.eren.ch\/barc\/author\/dfriedli\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/posts\/4786","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/comments?post=4786"}],"version-history":[{"count":0,"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/posts\/4786\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/media\/4794"}],"wp:attachment":[{"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/media?parent=4786"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/categories?post=4786"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eren.ch\/barc\/wp-json\/wp\/v2\/tags?post=4786"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}