{"id":548,"date":"2018-03-05T10:46:55","date_gmt":"2018-03-05T09:46:55","guid":{"rendered":"https:\/\/www.eren.ch\/cote\/?p=548"},"modified":"2018-04-16T16:50:48","modified_gmt":"2018-04-16T14:50:48","slug":"9-13-avril-camp-denfants-de-paques-inscription-ouverte","status":"publish","type":"post","link":"https:\/\/www.eren.ch\/cote\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\/","title":{"rendered":"(pass\u00e9) Camp d&rsquo;enfants de P\u00e2ques 2018"},"content":{"rendered":"<p style=\"text-align: left\"><img decoding=\"async\" class=\" wp-image-550 alignleft\" src=\"https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2018\/03\/IMG_5819-300x203.jpg\" alt=\"\" width=\"292\" height=\"198\" srcset=\"https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2018\/03\/IMG_5819-300x203.jpg 300w, https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2018\/03\/IMG_5819-768x520.jpg 768w, https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2018\/03\/IMG_5819-1024x694.jpg 1024w, https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2018\/03\/IMG_5819-1200x813.jpg 1200w, https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2018\/03\/IMG_5819.jpg 2000w\" sizes=\"(max-width: 292px) 85vw, 292px\" \/> <img decoding=\"async\" class=\"wp-image-551 alignright\" src=\"https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2018\/03\/IMG_5905-300x225.jpg\" alt=\"\" width=\"272\" height=\"204\" srcset=\"https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2018\/03\/IMG_5905-300x225.jpg 300w, https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2018\/03\/IMG_5905-768x576.jpg 768w, https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2018\/03\/IMG_5905-1024x768.jpg 1024w, https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2018\/03\/IMG_5905-1200x900.jpg 1200w, https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2018\/03\/IMG_5905.jpg 2000w\" sizes=\"(max-width: 272px) 85vw, 272px\" \/>Le traditionnel camp de P\u00e2ques pour les enfants et les pr\u00e9-ados prendra cette ann\u00e9e la direction des Emibois-Muriaux (JU). Du 9 au 13 avril, les enfants embarqueront \u00e0 la colonie des Ecarres pour vivre une aventure sur le th\u00e8me du \u00ab\u00a0Titanic 2\u00a0\u00bb. Pas d\u2019inqui\u00e9tude, aucun naufrage n\u2019est pr\u00e9vu\u00a0! Nous traverserons l\u2019Atlantique tout au long de la semaine gr\u00e2ce aux d\u00e9fis que rel\u00e8veront nos moussaillons. En parall\u00e8le des activit\u00e9s et des animations, les enfants (re-)vivront plusieurs histoires bibliques qui nous parlent de navigation et de d\u00e9couvertes surprenantes autour du th\u00e8me de l\u2019eau.<\/p>\n<p>Pour t\u00e9l\u00e9charger la circulaire, cliquer le lien suivant :\u00a0<a href=\"https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2018\/03\/Circulaire_La_Cote.pdf\">Circulaire_La_Cote<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le traditionnel camp de P\u00e2ques pour les enfants et les pr\u00e9-ados prendra cette ann\u00e9e la direction des Emibois-Muriaux (JU). Du 9 au 13 avril, les enfants embarqueront \u00e0 la colonie des Ecarres pour vivre une aventure sur le th\u00e8me du \u00ab\u00a0Titanic 2\u00a0\u00bb. Pas d\u2019inqui\u00e9tude, aucun naufrage n\u2019est pr\u00e9vu\u00a0! Nous traverserons l\u2019Atlantique tout au long de &hellip; <a href=\"https:\/\/www.eren.ch\/cote\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;(pass\u00e9) Camp d&rsquo;enfants de P\u00e2ques 2018&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-548","post","type-post","status-publish","format-standard","hentry","category-actualites"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>(pass\u00e9) Camp d&#039;enfants de P\u00e2ques 2018 - Paroisse de la C\u00f4te<\/title>\n<meta name=\"description\" content=\"Le traditionnel camp de P\u00e2ques pour les enfants et les pr\u00e9-ados prendra cette ann\u00e9e la direction des Emibois-Muriaux (JU). Du 9 au 13 avril, les enfants\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eren.ch\/cote\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"(pass\u00e9) Camp d&#039;enfants de P\u00e2ques 2018\" \/>\n<meta property=\"og:description\" content=\"Le traditionnel camp de P\u00e2ques pour les enfants et les pr\u00e9-ados prendra cette ann\u00e9e la direction des Emibois-Muriaux (JU). Du 9 au 13 avril, les enfants\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eren.ch\/cote\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\/\" \/>\n<meta property=\"og:site_name\" content=\"Paroisse de la C\u00f4te\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eglise.EREN\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-05T09:46:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-04-16T14:50:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2018\/03\/IMG_5819-300x203.jpg\" \/>\n<meta name=\"author\" content=\"Hyonou Paik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EgliseEREN\" \/>\n<meta name=\"twitter:site\" content=\"@EgliseEREN\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hyonou Paik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\\\/\"},\"author\":{\"name\":\"Hyonou Paik\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/#\\\/schema\\\/person\\\/302e7b3418694629dc425d8ca60bf06b\"},\"headline\":\"(pass\u00e9) Camp d&rsquo;enfants de P\u00e2ques 2018\",\"datePublished\":\"2018-03-05T09:46:55+00:00\",\"dateModified\":\"2018-04-16T14:50:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\\\/\"},\"wordCount\":125,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2018\\\/03\\\/IMG_5819-300x203.jpg\",\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\\\/\",\"url\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\\\/\",\"name\":\"(pass\u00e9) Camp d'enfants de P\u00e2ques 2018 - Paroisse de la C\u00f4te\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2018\\\/03\\\/IMG_5819-300x203.jpg\",\"datePublished\":\"2018-03-05T09:46:55+00:00\",\"dateModified\":\"2018-04-16T14:50:48+00:00\",\"description\":\"Le traditionnel camp de P\u00e2ques pour les enfants et les pr\u00e9-ados prendra cette ann\u00e9e la direction des Emibois-Muriaux (JU). Du 9 au 13 avril, les enfants\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eren.ch\\\/cote\\\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2018\\\/03\\\/IMG_5819.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2018\\\/03\\\/IMG_5819.jpg\",\"width\":2000,\"height\":1355},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"(pass\u00e9) Camp d&rsquo;enfants de P\u00e2ques 2018\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/#website\",\"url\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/\",\"name\":\"Paroisse de la C\u00f4te\",\"description\":\"La pr\u00e9sence protestante reconnue \u00e0 Peseux et Corcelles-Cormondr\u00e8che\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/#organization\",\"name\":\"Paroisse de La C\u00f4te\",\"url\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2019\\\/10\\\/logo-eren-carre.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2019\\\/10\\\/logo-eren-carre.jpg\",\"width\":512,\"height\":512,\"caption\":\"Paroisse de La C\u00f4te\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eglise.EREN\",\"https:\\\/\\\/x.com\\\/EgliseEREN\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/\u00c9glise_r\u00e9form\u00e9e_\u00e9vang\u00e9lique_du_canton_de_Neuch\u00e2tel\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/#\\\/schema\\\/person\\\/302e7b3418694629dc425d8ca60bf06b\",\"name\":\"Hyonou Paik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a4f79282244992058446eadb73490016939e53e9919ac01aa975800a876eb098?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a4f79282244992058446eadb73490016939e53e9919ac01aa975800a876eb098?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a4f79282244992058446eadb73490016939e53e9919ac01aa975800a876eb098?s=96&d=mm&r=g\",\"caption\":\"Hyonou Paik\"},\"url\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/author\\\/hpaik\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"(pass\u00e9) Camp d'enfants de P\u00e2ques 2018 - Paroisse de la C\u00f4te","description":"Le traditionnel camp de P\u00e2ques pour les enfants et les pr\u00e9-ados prendra cette ann\u00e9e la direction des Emibois-Muriaux (JU). Du 9 au 13 avril, les enfants","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eren.ch\/cote\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\/","og_locale":"fr_FR","og_type":"article","og_title":"(pass\u00e9) Camp d'enfants de P\u00e2ques 2018","og_description":"Le traditionnel camp de P\u00e2ques pour les enfants et les pr\u00e9-ados prendra cette ann\u00e9e la direction des Emibois-Muriaux (JU). Du 9 au 13 avril, les enfants","og_url":"https:\/\/www.eren.ch\/cote\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\/","og_site_name":"Paroisse de la C\u00f4te","article_publisher":"https:\/\/www.facebook.com\/eglise.EREN","article_published_time":"2018-03-05T09:46:55+00:00","article_modified_time":"2018-04-16T14:50:48+00:00","og_image":[{"url":"https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2018\/03\/IMG_5819-300x203.jpg","type":"","width":"","height":""}],"author":"Hyonou Paik","twitter_card":"summary_large_image","twitter_creator":"@EgliseEREN","twitter_site":"@EgliseEREN","twitter_misc":{"\u00c9crit par":"Hyonou Paik","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eren.ch\/cote\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\/#article","isPartOf":{"@id":"https:\/\/www.eren.ch\/cote\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\/"},"author":{"name":"Hyonou Paik","@id":"https:\/\/www.eren.ch\/cote\/#\/schema\/person\/302e7b3418694629dc425d8ca60bf06b"},"headline":"(pass\u00e9) Camp d&rsquo;enfants de P\u00e2ques 2018","datePublished":"2018-03-05T09:46:55+00:00","dateModified":"2018-04-16T14:50:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eren.ch\/cote\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\/"},"wordCount":125,"commentCount":0,"publisher":{"@id":"https:\/\/www.eren.ch\/cote\/#organization"},"image":{"@id":"https:\/\/www.eren.ch\/cote\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2018\/03\/IMG_5819-300x203.jpg","articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eren.ch\/cote\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\/","url":"https:\/\/www.eren.ch\/cote\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\/","name":"(pass\u00e9) Camp d'enfants de P\u00e2ques 2018 - Paroisse de la C\u00f4te","isPartOf":{"@id":"https:\/\/www.eren.ch\/cote\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eren.ch\/cote\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\/#primaryimage"},"image":{"@id":"https:\/\/www.eren.ch\/cote\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2018\/03\/IMG_5819-300x203.jpg","datePublished":"2018-03-05T09:46:55+00:00","dateModified":"2018-04-16T14:50:48+00:00","description":"Le traditionnel camp de P\u00e2ques pour les enfants et les pr\u00e9-ados prendra cette ann\u00e9e la direction des Emibois-Muriaux (JU). Du 9 au 13 avril, les enfants","breadcrumb":{"@id":"https:\/\/www.eren.ch\/cote\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eren.ch\/cote\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eren.ch\/cote\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\/#primaryimage","url":"https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2018\/03\/IMG_5819.jpg","contentUrl":"https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2018\/03\/IMG_5819.jpg","width":2000,"height":1355},{"@type":"BreadcrumbList","@id":"https:\/\/www.eren.ch\/cote\/9-13-avril-camp-denfants-de-paques-inscription-ouverte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.eren.ch\/cote\/"},{"@type":"ListItem","position":2,"name":"(pass\u00e9) Camp d&rsquo;enfants de P\u00e2ques 2018"}]},{"@type":"WebSite","@id":"https:\/\/www.eren.ch\/cote\/#website","url":"https:\/\/www.eren.ch\/cote\/","name":"Paroisse de la C\u00f4te","description":"La pr\u00e9sence protestante reconnue \u00e0 Peseux et Corcelles-Cormondr\u00e8che","publisher":{"@id":"https:\/\/www.eren.ch\/cote\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eren.ch\/cote\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.eren.ch\/cote\/#organization","name":"Paroisse de La C\u00f4te","url":"https:\/\/www.eren.ch\/cote\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eren.ch\/cote\/#\/schema\/logo\/image\/","url":"https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2019\/10\/logo-eren-carre.jpg","contentUrl":"https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2019\/10\/logo-eren-carre.jpg","width":512,"height":512,"caption":"Paroisse de La C\u00f4te"},"image":{"@id":"https:\/\/www.eren.ch\/cote\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eglise.EREN","https:\/\/x.com\/EgliseEREN","https:\/\/fr.wikipedia.org\/wiki\/\u00c9glise_r\u00e9form\u00e9e_\u00e9vang\u00e9lique_du_canton_de_Neuch\u00e2tel"]},{"@type":"Person","@id":"https:\/\/www.eren.ch\/cote\/#\/schema\/person\/302e7b3418694629dc425d8ca60bf06b","name":"Hyonou Paik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a4f79282244992058446eadb73490016939e53e9919ac01aa975800a876eb098?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a4f79282244992058446eadb73490016939e53e9919ac01aa975800a876eb098?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a4f79282244992058446eadb73490016939e53e9919ac01aa975800a876eb098?s=96&d=mm&r=g","caption":"Hyonou Paik"},"url":"https:\/\/www.eren.ch\/cote\/author\/hpaik\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eren.ch\/cote\/wp-json\/wp\/v2\/posts\/548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eren.ch\/cote\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eren.ch\/cote\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eren.ch\/cote\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eren.ch\/cote\/wp-json\/wp\/v2\/comments?post=548"}],"version-history":[{"count":0,"href":"https:\/\/www.eren.ch\/cote\/wp-json\/wp\/v2\/posts\/548\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eren.ch\/cote\/wp-json\/wp\/v2\/media?parent=548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eren.ch\/cote\/wp-json\/wp\/v2\/categories?post=548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eren.ch\/cote\/wp-json\/wp\/v2\/tags?post=548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}