{"id":594,"date":"2018-06-27T17:48:31","date_gmt":"2018-06-27T15:48:31","guid":{"rendered":"https:\/\/www.eren.ch\/cote\/?p=594"},"modified":"2018-08-27T13:55:49","modified_gmt":"2018-08-27T11:55:49","slug":"quatre-cultes-dete-thematiques","status":"publish","type":"post","link":"https:\/\/www.eren.ch\/cote\/quatre-cultes-dete-thematiques\/","title":{"rendered":"(pass\u00e9) Quatre cultes d&rsquo;\u00e9t\u00e9 th\u00e9matiques"},"content":{"rendered":"<p><img decoding=\"async\" class=\" wp-image-595 alignleft\" src=\"https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2018\/06\/Se\u0301rie-cultes-_The\u0300ses_-214x300.png\" alt=\"\" width=\"296\" height=\"415\" srcset=\"https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2018\/06\/Se\u0301rie-cultes-_The\u0300ses_-214x300.png 214w, https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2018\/06\/Se\u0301rie-cultes-_The\u0300ses_.png 480w\" sizes=\"(max-width: 296px) 85vw, 296px\" \/>Dans le cadre de la festivit\u00e9 de 500 ans de la R\u00e9forme, les \u00c9glises membres de la F\u00e9d\u00e9ration des \u00c9glises protestantes de Suisse ont voulu renouveler le geste des R\u00e9formateurs en formulant de nouvelles th\u00e8ses, avec un langage d\u2019aujourd\u2019hui, pour l\u2019\u00c9vangile. En profitant du temps estival, la paroisse de la C\u00f4te souhaite vivre une s\u00e9rie de cultes avec les th\u00e8ses r\u00e9dig\u00e9es par les diff\u00e9rents groupes de notre canton et adopt\u00e9es par le Conseil synodal de notre \u00c9glise.<\/p>\n<p>(Pour t\u00e9l\u00e9charger le programme : <a href=\"http:\/\/drive.google.com\/open?id=1i2xq_G3pcKy_qYaMaIw3MO-Z7W7DtIyr\" target=\"_blank\" rel=\"noopener\">CLIQUER ICI<\/a>)<\/p>\n<p>Quatre dimanche \u00e0 10h\u00a0:<\/p>\n<p><strong>le 22 juillet, temple de Peseux\u00a0: \u00ab\u00a0Il n\u2019y a pas de nuls aux yeux de Dieu\u00a0\u00bb<\/strong><\/p>\n<p><strong>le 29 juillet, temple de Corcelles\u00a0: \u00ab\u00a0Vivre ensemble, c\u2019est possible\u00a0\u00bb<\/strong><\/p>\n<p><strong>le 5 ao\u00fbt, temple de Peseux\u00a0: \u00ab\u00a0Dieu parle \u00e0 moi, \u00e0 toi, \u00e0 nous\u00a0\u00bb<\/strong><\/p>\n<p><strong>le 12 ao\u00fbt, temple de Corcelles\u00a0: \u00ab\u00a0\u0152uvrer ensemble, Dieu nous y appelle\u00a0\u00bb<\/strong><\/p>\n<p>Bienvenue \u00e0 tous !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dans le cadre de la festivit\u00e9 de 500 ans de la R\u00e9forme, les \u00c9glises membres de la F\u00e9d\u00e9ration des \u00c9glises protestantes de Suisse ont voulu renouveler le geste des R\u00e9formateurs en formulant de nouvelles th\u00e8ses, avec un langage d\u2019aujourd\u2019hui, pour l\u2019\u00c9vangile. En profitant du temps estival, la paroisse de la C\u00f4te souhaite vivre une s\u00e9rie &hellip; <a href=\"https:\/\/www.eren.ch\/cote\/quatre-cultes-dete-thematiques\/\" class=\"more-link\">Continuer la lecture<span class=\"screen-reader-text\"> de &laquo;&nbsp;(pass\u00e9) Quatre cultes d&rsquo;\u00e9t\u00e9 th\u00e9matiques&nbsp;&raquo;<\/span><\/a><\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":["post-594","post","type-post","status-publish","format-standard","hentry","category-actualites"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>(pass\u00e9) Quatre cultes d&#039;\u00e9t\u00e9 th\u00e9matiques - Paroisse de la C\u00f4te<\/title>\n<meta name=\"description\" content=\"Dans le cadre de la festivit\u00e9 de 500 ans de la R\u00e9forme, les \u00c9glises membres de la F\u00e9d\u00e9ration des \u00c9glises protestantes de Suisse ont voulu renouveler le\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eren.ch\/cote\/quatre-cultes-dete-thematiques\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"(pass\u00e9) Quatre cultes d&#039;\u00e9t\u00e9 th\u00e9matiques\" \/>\n<meta property=\"og:description\" content=\"Dans le cadre de la festivit\u00e9 de 500 ans de la R\u00e9forme, les \u00c9glises membres de la F\u00e9d\u00e9ration des \u00c9glises protestantes de Suisse ont voulu renouveler le\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eren.ch\/cote\/quatre-cultes-dete-thematiques\/\" \/>\n<meta property=\"og:site_name\" content=\"Paroisse de la C\u00f4te\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/eglise.EREN\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-27T15:48:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-08-27T11:55:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2018\/06\/Se\u0301rie-cultes-_The\u0300ses_-214x300.png\" \/>\n<meta name=\"author\" content=\"Hyonou Paik\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@EgliseEREN\" \/>\n<meta name=\"twitter:site\" content=\"@EgliseEREN\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Hyonou Paik\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/quatre-cultes-dete-thematiques\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/quatre-cultes-dete-thematiques\\\/\"},\"author\":{\"name\":\"Hyonou Paik\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/#\\\/schema\\\/person\\\/0c0a494a8f8bb282b37012cd2b7af77b\"},\"headline\":\"(pass\u00e9) Quatre cultes d&rsquo;\u00e9t\u00e9 th\u00e9matiques\",\"datePublished\":\"2018-06-27T15:48:31+00:00\",\"dateModified\":\"2018-08-27T11:55:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/quatre-cultes-dete-thematiques\\\/\"},\"wordCount\":160,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/#organization\"},\"articleSection\":[\"Actualit\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/quatre-cultes-dete-thematiques\\\/\",\"url\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/quatre-cultes-dete-thematiques\\\/\",\"name\":\"(pass\u00e9) Quatre cultes d'\u00e9t\u00e9 th\u00e9matiques - Paroisse de la C\u00f4te\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/#website\"},\"datePublished\":\"2018-06-27T15:48:31+00:00\",\"dateModified\":\"2018-08-27T11:55:49+00:00\",\"description\":\"Dans le cadre de la festivit\u00e9 de 500 ans de la R\u00e9forme, les \u00c9glises membres de la F\u00e9d\u00e9ration des \u00c9glises protestantes de Suisse ont voulu renouveler le\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/quatre-cultes-dete-thematiques\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.eren.ch\\\/cote\\\/quatre-cultes-dete-thematiques\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/quatre-cultes-dete-thematiques\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"(pass\u00e9) Quatre cultes d&rsquo;\u00e9t\u00e9 th\u00e9matiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/#website\",\"url\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/\",\"name\":\"Paroisse de la C\u00f4te\",\"description\":\"La pr\u00e9sence protestante reconnue \u00e0 Peseux et Corcelles-Cormondr\u00e8che\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/#organization\",\"name\":\"Paroisse de La C\u00f4te\",\"url\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2019\\\/10\\\/logo-eren-carre.jpg\",\"contentUrl\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2019\\\/10\\\/logo-eren-carre.jpg\",\"width\":512,\"height\":512,\"caption\":\"Paroisse de La C\u00f4te\"},\"image\":{\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/eglise.EREN\",\"https:\\\/\\\/x.com\\\/EgliseEREN\",\"https:\\\/\\\/fr.wikipedia.org\\\/wiki\\\/\u00c9glise_r\u00e9form\u00e9e_\u00e9vang\u00e9lique_du_canton_de_Neuch\u00e2tel\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/#\\\/schema\\\/person\\\/0c0a494a8f8bb282b37012cd2b7af77b\",\"name\":\"Hyonou Paik\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a4f79282244992058446eadb73490016939e53e9919ac01aa975800a876eb098?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a4f79282244992058446eadb73490016939e53e9919ac01aa975800a876eb098?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a4f79282244992058446eadb73490016939e53e9919ac01aa975800a876eb098?s=96&d=mm&r=g\",\"caption\":\"Hyonou Paik\"},\"url\":\"https:\\\/\\\/www.eren.ch\\\/cote\\\/author\\\/hpaik\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"(pass\u00e9) Quatre cultes d'\u00e9t\u00e9 th\u00e9matiques - Paroisse de la C\u00f4te","description":"Dans le cadre de la festivit\u00e9 de 500 ans de la R\u00e9forme, les \u00c9glises membres de la F\u00e9d\u00e9ration des \u00c9glises protestantes de Suisse ont voulu renouveler le","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eren.ch\/cote\/quatre-cultes-dete-thematiques\/","og_locale":"fr_FR","og_type":"article","og_title":"(pass\u00e9) Quatre cultes d'\u00e9t\u00e9 th\u00e9matiques","og_description":"Dans le cadre de la festivit\u00e9 de 500 ans de la R\u00e9forme, les \u00c9glises membres de la F\u00e9d\u00e9ration des \u00c9glises protestantes de Suisse ont voulu renouveler le","og_url":"https:\/\/www.eren.ch\/cote\/quatre-cultes-dete-thematiques\/","og_site_name":"Paroisse de la C\u00f4te","article_publisher":"https:\/\/www.facebook.com\/eglise.EREN","article_published_time":"2018-06-27T15:48:31+00:00","article_modified_time":"2018-08-27T11:55:49+00:00","og_image":[{"url":"https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2018\/06\/Se\u0301rie-cultes-_The\u0300ses_-214x300.png","type":"","width":"","height":""}],"author":"Hyonou Paik","twitter_card":"summary_large_image","twitter_creator":"@EgliseEREN","twitter_site":"@EgliseEREN","twitter_misc":{"\u00c9crit par":"Hyonou Paik","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.eren.ch\/cote\/quatre-cultes-dete-thematiques\/#article","isPartOf":{"@id":"https:\/\/www.eren.ch\/cote\/quatre-cultes-dete-thematiques\/"},"author":{"name":"Hyonou Paik","@id":"https:\/\/www.eren.ch\/cote\/#\/schema\/person\/0c0a494a8f8bb282b37012cd2b7af77b"},"headline":"(pass\u00e9) Quatre cultes d&rsquo;\u00e9t\u00e9 th\u00e9matiques","datePublished":"2018-06-27T15:48:31+00:00","dateModified":"2018-08-27T11:55:49+00:00","mainEntityOfPage":{"@id":"https:\/\/www.eren.ch\/cote\/quatre-cultes-dete-thematiques\/"},"wordCount":160,"commentCount":0,"publisher":{"@id":"https:\/\/www.eren.ch\/cote\/#organization"},"articleSection":["Actualit\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.eren.ch\/cote\/quatre-cultes-dete-thematiques\/","url":"https:\/\/www.eren.ch\/cote\/quatre-cultes-dete-thematiques\/","name":"(pass\u00e9) Quatre cultes d'\u00e9t\u00e9 th\u00e9matiques - Paroisse de la C\u00f4te","isPartOf":{"@id":"https:\/\/www.eren.ch\/cote\/#website"},"datePublished":"2018-06-27T15:48:31+00:00","dateModified":"2018-08-27T11:55:49+00:00","description":"Dans le cadre de la festivit\u00e9 de 500 ans de la R\u00e9forme, les \u00c9glises membres de la F\u00e9d\u00e9ration des \u00c9glises protestantes de Suisse ont voulu renouveler le","breadcrumb":{"@id":"https:\/\/www.eren.ch\/cote\/quatre-cultes-dete-thematiques\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eren.ch\/cote\/quatre-cultes-dete-thematiques\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.eren.ch\/cote\/quatre-cultes-dete-thematiques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.eren.ch\/cote\/"},{"@type":"ListItem","position":2,"name":"(pass\u00e9) Quatre cultes d&rsquo;\u00e9t\u00e9 th\u00e9matiques"}]},{"@type":"WebSite","@id":"https:\/\/www.eren.ch\/cote\/#website","url":"https:\/\/www.eren.ch\/cote\/","name":"Paroisse de la C\u00f4te","description":"La pr\u00e9sence protestante reconnue \u00e0 Peseux et Corcelles-Cormondr\u00e8che","publisher":{"@id":"https:\/\/www.eren.ch\/cote\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eren.ch\/cote\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.eren.ch\/cote\/#organization","name":"Paroisse de La C\u00f4te","url":"https:\/\/www.eren.ch\/cote\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.eren.ch\/cote\/#\/schema\/logo\/image\/","url":"https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2019\/10\/logo-eren-carre.jpg","contentUrl":"https:\/\/www.eren.ch\/cote\/wp-content\/uploads\/sites\/5\/2019\/10\/logo-eren-carre.jpg","width":512,"height":512,"caption":"Paroisse de La C\u00f4te"},"image":{"@id":"https:\/\/www.eren.ch\/cote\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/eglise.EREN","https:\/\/x.com\/EgliseEREN","https:\/\/fr.wikipedia.org\/wiki\/\u00c9glise_r\u00e9form\u00e9e_\u00e9vang\u00e9lique_du_canton_de_Neuch\u00e2tel"]},{"@type":"Person","@id":"https:\/\/www.eren.ch\/cote\/#\/schema\/person\/0c0a494a8f8bb282b37012cd2b7af77b","name":"Hyonou Paik","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/a4f79282244992058446eadb73490016939e53e9919ac01aa975800a876eb098?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a4f79282244992058446eadb73490016939e53e9919ac01aa975800a876eb098?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a4f79282244992058446eadb73490016939e53e9919ac01aa975800a876eb098?s=96&d=mm&r=g","caption":"Hyonou Paik"},"url":"https:\/\/www.eren.ch\/cote\/author\/hpaik\/"}]}},"_links":{"self":[{"href":"https:\/\/www.eren.ch\/cote\/wp-json\/wp\/v2\/posts\/594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eren.ch\/cote\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.eren.ch\/cote\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.eren.ch\/cote\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.eren.ch\/cote\/wp-json\/wp\/v2\/comments?post=594"}],"version-history":[{"count":0,"href":"https:\/\/www.eren.ch\/cote\/wp-json\/wp\/v2\/posts\/594\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.eren.ch\/cote\/wp-json\/wp\/v2\/media?parent=594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.eren.ch\/cote\/wp-json\/wp\/v2\/categories?post=594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.eren.ch\/cote\/wp-json\/wp\/v2\/tags?post=594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}